{"id":13455,"date":"2024-12-12T11:38:17","date_gmt":"2024-12-12T19:38:17","guid":{"rendered":"https:\/\/www.soundcu.com\/?page_id=13455"},"modified":"2025-11-20T09:30:32","modified_gmt":"2025-11-20T17:30:32","slug":"heloc","status":"publish","type":"page","link":"https:\/\/www.soundcu.com\/es\/heloc\/","title":{"rendered":"L\u00ednea de cr\u00e9dito hipotecario"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__blue co-flex_row__lead-capture-hero co-flex_row__next_row__sticky-nav\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"co-lead_capture_hero  co-lead_capture_hero__has_image benefits\" aria-label=\"Encabezado: Financie un nuevo comienzo con una s\u00f3lida l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC).\">\n\t\t<div class=\"co-lead_capture_hero--inner\">\n\t\t\t<div class=\"prow items-center\">\n\t\t\t\t<div class=\"co-lead_capture_hero--text pcol-lg:6 pcol-xl:6\">\n\t\t\t\t\t<h1 class=\"co-lead_capture_hero--title\" >Financia un nuevo comienzo con una s\u00f3lida l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC).<\/h1>\t\t\t\t\t<p class=\"co-lead_capture_hero--tagline\">L\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC)<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-lead_capture_hero--img_wrap pcol-lg:6 pcol-xl:6\">\n\t\t\t\t\t\t<svg class=\"co-branch_location_hero--svg-gradient\" width=\"159.2\" height=\"609\" viewbox=\"0 0 159.2 609\">\n  <defs>\n   <clippath id=\"clip-path-hero-gradient\">\n    <path d=\"M0,0H159.2V609H0Z\" fill=\"none\"\/>\n   <\/clippath>\n   <lineargradient id=\"linear-gradient-hero\" x1=\"1\" y1=\"1\" x2=\"1.147\" gradientunits=\"objectBoundingBox\">\n    <stop offset=\"0\" stop-color=\"#0d2c6c\"\/>\n    <stop offset=\"1\" stop-color=\"#67ccf2\"\/>\n   <\/lineargradient>\n  <\/defs>\n  <g transform=\"translate(487 -10)\">\n   <g transform=\"translate(-487 10)\" clip-path=\"url(#clip-path-hero-gradient)\">\n    <path d=\"M148.955,0H96.92c-232.639,458.1,26.61,607.908,26.61,607.908h25.425s-249.534-124.9,0-607.908\" transform=\"translate(0)\" fill=\"url(#linear-gradient-hero)\"\/>\n     <path d=\"M747.31,0Z\" transform=\"translate(246.995)\" fill=\"#040504\"\/>\n   <\/g>\n  <\/g>\n<\/svg>\n<div class=\"co-lead_capture_hero--mask\"><svg width=\"997.021\" height=\"609\" viewbox=\"0 0 997.021 609\"><defs><clippath id=\"svgPathHero\"><path d=\"M144.231,0c-260.172,483.012,0,607.908,0,607.908L1025.62,609V0Z\" transform=\"translate(-28.599)\"\/><\/clippath><\/defs><image id=\"image_6a576bba112a1\" xlink:href=\"https:\/\/www.soundcu.com\/files\/iStock-1397373481_944x612-941x610.jpg\" src=\"https:\/\/www.soundcu.com\/files\/iStock-1397373481_944x612-941x610.jpg\" clip-path=\"url(#svgPathHero)\"  alt=\"reasons for personal loans\" \/><\/svg><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<svg class=\"co-blog_hero--svg-line\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1435.942\" height=\"195.217\" viewbox=\"0 0 1435.942 195.217\">\n  <defs>\n    <clippath id=\"blog_hero-clip_path\">\n      <path d=\"M0,387.736C211.1,511.3,411.942,533.1,605.539,522.95c108.631-5.7,214.966-26.324,319.519-54.981C417.606,553.271,174.676,425.584,0,336.3Z\"\/>\n    <\/clippath>\n    <lineargradient id=\"blog_hero-linear_gradient\" x1=\"0.845\" y1=\"0.629\" x2=\"0.08\" y2=\"0.361\" gradientunits=\"objectBoundingBox\">\n      <stop offset=\"0\" stop-color=\"#0d2c6c\"\/>\n      <stop offset=\"1\" stop-color=\"#67ccf2\"\/>\n    <\/lineargradient>\n  <\/defs>\n  <g transform=\"translate(-2643 -1494)\">\n    <path d=\"M605.539,522.95C411.942,533.1,211.1,511.3,0,387.737V529.83H1435.942V334.613C1240.4,400.9,1071.692,443.32,925.057,467.969c-104.552,28.656-210.888,49.283-319.518,54.981\" transform=\"translate(2643 1159.387)\" fill=\"#f2fafc\"\/>\n    <g transform=\"translate(2643 1159.387)\" clip-path=\"url(#blog_hero-clip_path)\">\n      <path d=\"M901.455,259.213-64.733,341.84,23.6,630.362l966.188-82.627Z\" fill=\"url(#blog_hero-linear_gradient)\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\n\t<\/header>\n\t<div class=\"co-benefits-hero benefits\">\n\t\t<div class=\"co-row\">\n\t\t\t<div class=\"prow\">\n\t\t\t\t<div class=\"pcol-lg:7 co-benefits-hero--col__info\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-benefits-hero--description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-benefits-hero--description_head\">Flexibilidad, f\u00e1cil acceso a los fondos y posibles beneficios fiscales.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-benefits-hero--description_text\"><p>Al igual que una tarjeta de cr\u00e9dito, una l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC) es una l\u00ednea de cr\u00e9dito rotativa, lo que significa que puede pedir prestado, reembolsar y volver a pedir prestado hasta el l\u00edmite de cr\u00e9dito aprobado durante el per\u00edodo de disposici\u00f3n.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pcol-lg:5 co-benefits-hero--col__form\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-benefits-hero--button_wrap\">\n\t\t\t\t\t\t<a class=\"co-benefits-hero--button\" href=\"https:\/\/app.loanspq.com\/he\/HomeEquityLoan.aspx?lenderref=soundcu082521&#038;_ga=2.142049202.1490978376.1715007655-1124716528.1711565775&#038;_gl=1*183b425*_ga*MTEyNDcxNjUyOC4xNzExNTY1Nzc1*_ga_FR6440DWJ8*MTcxNTAyNTY2OC43MS4xLjE3MTUwMzAzODQuNTcuMC4w\" rel=\"noopener\">Solicita una l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC).<\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-benefits-hero--promo\">\n\t\t\t\t\t\t\t<h2>Est\u00e1s justo donde debes estar. Hazlo perfecto con una l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria.<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__sticky-nav co-flex_row__next_row__columns\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-sticky_nav_wrap is-active\" id=\"js-sticky_nav_wrap\">\n\t\t<nav\n\t\t\tclass=\"co-sticky_nav\"\n\t\t\tid=\"js-sticky_nav\"\n\t\t\taria-label=\"en la navegaci\u00f3n de anclaje de p\u00e1gina\"\n\t\t>\n\t\t\t<div class=\"co-sticky_nav--mobile\">\n\t\t\t\t<button\n\t\t\t\t\tclass=\"co-sticky_nav--toggle\"\n\t\t\t\t\tid=\"js-sticky_nav_toggle\"\n\t\t\t\t\taria-label=\"Abrir y cerrar men\u00fa de p\u00e1gina\"\n\t\t\t\t>Men\u00fa de p\u00e1gina<\/button>\n\t\t\t<\/div>\n\t\t\t<div\n\t\t\t\tclass=\"co-sticky_nav--row co-row\"\n\t\t\t\tid=\"js-sticky_nav_links\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#rates\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\ttasas de interes\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#benefits\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\tBeneficios\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#faq\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\tPreguntas frecuentes\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#apply\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\tAplicar\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__next_row_diff co-flex_row__columns co-flex_row__next_row__long-form-text\" id=\"benefits\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-columns\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Utilice el capital acumulado en su vivienda para reformar la que necesita reparaciones, cubrir gastos importantes o consolidar deudas.<\/h2><div class=\"co-intro_text--intro\"><p>&nbsp;<\/p>\n<\/div>\t\t<\/header>\n\t\t\t\t<div class=\"co-columns--row prow prow-md:2 prow-lg:3 co-columns--row__icons justify-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconDollarSign\"\n\t\tviewbox=\"0 0 72.211 72.21\"\n\t\twidth=\"72.211\"\n\t\theight=\"72.21\"\n\t>\n\t\t<title>Dollar Sign<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-914.164 -626.336)\">\n\t\t\t<path d=\"M3716.695,2178.253l-5.983,5.983h.72a5.464,5.464,0,0,1,5.509,5.09,5.366,5.366,0,0,1-5.354,5.63h-3.574a5.366,5.366,0,0,1-5.359-5.36h-7.146c0,.292.013.581.033.868a12.519,12.519,0,0,0,10.687,11.509v.13a3.573,3.573,0,1,0,7.146,0v-.13a12.457,12.457,0,0,0,3.321-23.72\" transform=\"translate(-2760.671 -1518.222)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3702.923,2093.54l5.991-5.991h-.745a5.462,5.462,0,0,1-5.509-5.09,5.365,5.365,0,0,1,5.353-5.63h3.573a5.365,5.365,0,0,1,5.36,5.36h7.146c0-.284-.013-.565-.032-.844a12.516,12.516,0,0,0-10.688-11.533v-.13a3.573,3.573,0,0,0-7.146,0v.13a12.457,12.457,0,0,0-3.3,23.727\" transform=\"translate(-2760.67 -1428.682)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3720.04,2134.98l-7.558,7.559-5.991,5.991-6.515,6.516h6.246a5.324,5.324,0,0,0,.481,2.216l7.576-7.576,5.983-5.983,6.523-6.523h-6.271a5.324,5.324,0,0,0-.474-2.2\" transform=\"translate(-2764.238 -1483.671)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M3661.2,2030.745a4.183,4.183,0,0,0-7.446,3.812,27.742,27.742,0,0,1-42.579,33.839l4.876-4.877a12.427,12.427,0,0,1-2.4-6.539l-6.817,6.817a27.744,27.744,0,0,1,38.833-38.833l-5.891,5.89a12.439,12.439,0,0,1,2.4,6.548l5.967-5.967,2.127-2.127,1.36-1.36c3.19-4.81,1.035-7.931-.557-9.379a36.053,36.053,0,1,0,10.134,12.177\" transform=\"translate(-2678.772 -1384.739)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Sin cargos iniciales<\/h3><div class=\"co-columns--box_desc\"><p>Sin tasas de solicitud, tasas de tramitaci\u00f3n ni gastos de cierre.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconArrowsUpDown\"\n\t\tviewbox=\"0 0 74.214 71.041\"\n\t\twidth=\"74.214\"\n\t\theight=\"71.041\"\n\t>\n\t\t<title>Arrows Up &amp; Down<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-190 -816.756)\">\n\t\t\t<path d=\"M115.662,3035.821a19.089,19.089,0,1,0,19.089,19.089,19.111,19.111,0,0,0-19.089-19.089m0,35.076a15.987,15.987,0,1,1,15.987-15.987,16.005,16.005,0,0,1-15.987,15.987\" transform=\"translate(112.892 -2202.945)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M166.012,3075.169h1.469a2.329,2.329,0,0,1,2.327,2.327h3.1a5.437,5.437,0,0,0-4.653-5.373v-2.4a.758.758,0,0,0-.758-.758h-1.586a.758.758,0,0,0-.758.758v2.4a5.436,5.436,0,0,0-4.65,5.58,5.512,5.512,0,0,0,5.551,5.221H167.4a2.382,2.382,0,0,1,2.4,2.167,2.329,2.329,0,0,1-2.321,2.486H165.93a2.329,2.329,0,0,1-2.327-2.327h-3.1a5.436,5.436,0,0,0,4.654,5.373v2.285a.874.874,0,0,0,.874.874h1.355a.874.874,0,0,0,.874-.874v-2.285a5.436,5.436,0,0,0,4.649-5.58,5.512,5.512,0,0,0-5.551-5.221H165.93a2.329,2.329,0,0,1-2.321-2.486,2.382,2.382,0,0,1,2.4-2.167\" transform=\"translate(61.849 -2229.409)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M146.579,3015.109v-24.868h5.315l-9.285-13.923-10.492,13.923h5.154v24.868a18.8,18.8,0,0,1-34.206,10.792l-5.777,7.666a28.088,28.088,0,0,0,49.29-18.458\" transform=\"translate(112.32 -2155.436)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M9.285,3022.758l10.492-13.924H14.622v-24.867a18.8,18.8,0,0,1,34.206-10.792l5.777-7.666a28.088,28.088,0,0,0-49.29,18.458v24.867H0Z\" transform=\"translate(190 -2139.087)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Flexibilidad <\/h3><div class=\"co-columns--box_desc\"><p>Pide prestado lo que necesites cuando lo necesites.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconATM\"\n\t\tviewbox=\"0 0 66.742 69.624\"\n\t\twidth=\"66.742\"\n\t\theight=\"69.624\"\n\t>\n\t\t<title>ATM<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-963.171 -221.557)\">\n\t\t\t<path d=\"M3836.088,23.077V2.764h66.742V23.077a2.9,2.9,0,1,1-5.8,0V8.568h-55.135V23.077a2.9,2.9,0,1,1-5.8,0\" transform=\"translate(-2872.917 218.792)\" fill=\"#efc025\"\/>\n\t\t\t<rect width=\"5.804\" height=\"20.313\" transform=\"translate(983.484 230.262)\" fill=\"#00205b\"\/>\n\t\t\t<rect width=\"5.804\" height=\"14.509\" transform=\"translate(983.484 253.477)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M4066.448,106.874h5.8a2.9,2.9,0,0,0,2.9-2.9V45.956h-8.705Z\" transform=\"translate(-3056.847 184.306)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M3916.892,45.956h-23.215v58.016a2.9,2.9,0,0,0,2.9,2.9h20.313Zm-14.509,0h5.8V66.269h-5.8Zm0,23.215h5.8V83.68h-5.8Z\" transform=\"translate(-2918.899 184.306)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M4008.858,45.957v60.918h11.607V45.957Z\" transform=\"translate(-3010.865 184.305)\" fill=\"#00205b\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >F\u00e1cil acceso a los fondos<\/h3><div class=\"co-columns--box_desc\"><p>Acceda a su l\u00ednea de cr\u00e9dito con su tarjeta de cr\u00e9dito Equity o mediante una transferencia de saldo en l\u00ednea.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__next_row_diff co-flex_row__long-form-text co-flex_row__next_row__faqs\" id=\"rates\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-long_form\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Obtenga hoy la mejor tasa de inter\u00e9s para su l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC).<\/h2>\t\t<\/header>\n\t\t\t\t<div class=\"co-long_form--block co-long_form--block__nomedia prow items-start\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:8\">\n\t\t\t\t\t<div class=\"co-long_form--content\"><div class=\"co-rates_table_wrap co-rates_table_wrap__rates_list\">\n\t<table class=\"co-rates_table\">\n\t\t<caption class=\"co-rates_table_wrap--title\" id=\"homeequitylinesofcredit\">\n\t\t\tL\u00edneas de cr\u00e9dito con garant\u00eda hipotecaria sobre la vivienda\t\t<\/caption>\n\t\t\t\t\t<thead>\n\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>LTV&nbsp;<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t\t\t<th\n\t\t\t\t\t\t\tclass=\"co-rates_table--heading\"\n\t\t\t\t\t\t\tscope=\"col\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<p>Rango de TAE*<\/p>\t\t\t\t\t\t<\/th>\n\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t\t<tr>\n\t\t\t\t\t<td class=\"co-rates_table--foot_cell\" colspan=\"2\">\n\t\t\t\t\t\t<div class=\"small-text\">\n<p style=\"text-align: left;\"><strong><sup>6<\/sup>Pr\u00e9stamos con garant\u00eda hipotecaria y l\u00edneas de cr\u00e9dito con garant\u00eda hipotecaria:<\/strong><br \/>\nFinanciamiento disponible para viviendas en WA, OR o ID. Se aplica una comisi\u00f3n por cancelaci\u00f3n anticipada de $525 si el pr\u00e9stamo se cancela dentro de los primeros 24 meses. El pago mensual m\u00ednimo se calcula en 0.75% del saldo total adeudado. El monto m\u00e1ximo del pr\u00e9stamo est\u00e1 determinado por el capital acumulado en su vivienda. La l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria tiene una tasa variable basada en la tasa Prime, publicada en el Wall Street Journal, y est\u00e1 sujeta a cambios durante el plazo del pr\u00e9stamo. La TAE m\u00ednima es de 3.99% y la TAE m\u00e1xima es de 18%. La mayor\u00eda de los pr\u00e9stamos con garant\u00eda hipotecaria califican para intereses deducibles. Consulte a su asesor fiscal para obtener m\u00e1s detalles. Se requiere seguro de vivienda.<\/p>\n<p style=\"text-align: left;\">Para un valor tasado de 81% a 90%, solicite hasta un m\u00e1ximo de $50,000 para pr\u00e9stamos sobre capital de vivienda y l\u00edneas de cr\u00e9dito sobre capital de vivienda. Pr\u00e9stamos sobre capital de vivienda fijos no ocupados por el propietario: LTV m\u00e1ximo 70% con un monto m\u00e1ximo de pr\u00e9stamo de $150,000. Tasas de HELOC no ocupadas por el propietario: APR Prime +2% a Prime +4%; LTV m\u00e1ximo 70% con un monto m\u00e1ximo de pr\u00e9stamo de $150,000.<\/p>\n<p style=\"text-align: left;\">Las tarifas y los cargos est\u00e1n sujetos a cambios. Por favor, consulte con\u00a0<a href=\"https:\/\/www.soundcu.com\/es\/branches\/\">su sucursal local<\/a>, o ll\u00e1menos si podemos responder a alguna pregunta.<\/p>\n<\/div>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/tfoot>\n\t\t\t\t\t<tbody>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>LTV&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>Hasta 70% LTV<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Rango de TAE*<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>6,75% \u2013 9,75%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>LTV&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>70% \u2013 80% LTV<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Rango de TAE*<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>7,75% \u2013 9,75%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t\t\t<tr class=\"co-rates_table--row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>LTV&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>80% \u2013 90% LTV<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<td class=\"co-rates_table--cell\">\n\t\t\t\t\t\t\t\t<div class=\"co-rates_table--cell_mobile_title\">\n\t\t\t\t\t\t\t\t\t<p>Rango de TAE*<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<p>9.75% \u2013 9.75%<\/p>\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t\t\t\t\t<\/tbody>\n\t\t\t<\/table>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__faqs co-flex_row__next_row__single-path-cta\" id=\"faq\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<section class=\"co-accords_section\" aria-label=\"Preguntas frecuentes sobre las l\u00edneas de cr\u00e9dito con garant\u00eda hipotecaria (HELOC)\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Preguntas frecuentes sobre las l\u00edneas de cr\u00e9dito con garant\u00eda hipotecaria (HELOC)<\/h2>\t\t<\/header>\n\t\t\t<div class=\"co-accordion\" data-animation=\"on\" data-multi-items=\"on\">\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4077\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfQu\u00e9 son los pr\u00e9stamos con garant\u00eda hipotecaria?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>Un pr\u00e9stamo con garant\u00eda hipotecaria es un pr\u00e9stamo al consumo respaldado por una segunda hipoteca, que permite a los propietarios obtener financiaci\u00f3n utilizando el valor acumulado de su vivienda como garant\u00eda. Se recomienda su uso para gastos recurrentes a largo plazo, como reformas del hogar, facturas m\u00e9dicas o la matr\u00edcula universitaria.<\/p>\n<p>Sound Credit Union ofrece <a href=\"https:\/\/www.soundcu.com\/es\/personal\/home-loans\/equity\/\">pr\u00e9stamos con garant\u00eda hipotecaria<\/a>.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4079\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfC\u00f3mo funcionan los pr\u00e9stamos con garant\u00eda hipotecaria?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>Los pr\u00e9stamos con garant\u00eda hipotecaria utilizan el capital acumulado en su vivienda (la diferencia entre el valor de su vivienda y el saldo de su hipoteca) como garant\u00eda para el pr\u00e9stamo.<\/p>\n<p>Sound Credit Union ofrece <a href=\"https:\/\/www.soundcu.com\/es\/personal\/home-loans\/equity\/\">pr\u00e9stamos con garant\u00eda hipotecaria<\/a>.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4080\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfQu\u00e9 compras pueden optar a un pr\u00e9stamo hipotecario ecol\u00f3gico?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<ul>\n<li>Sistemas de calefacci\u00f3n y refrigeraci\u00f3n<\/li>\n<li>Windows<\/li>\n<li>Sistemas de calentamiento de agua<\/li>\n<li>Accesorios<\/li>\n<li>Aislamiento, sellado de aire y conductos<\/li>\n<li>energ\u00eda solar y e\u00f3lica<\/li>\n<li>Claraboyas y tubos solares<\/li>\n<li>Jardiner\u00eda xer\u00f3fila: paisajes que requieren poca agua.<\/li>\n<li>conversiones a gas<\/li>\n<\/ul>\n<p>Otros proyectos respetuosos con el medio ambiente se estudiar\u00e1n caso por caso.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4034\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfCu\u00e1les son las opciones de pago para los pr\u00e9stamos de Sound?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<h2>Formas de realizar el pago de su pr\u00e9stamo<\/h2>\n<p>Es f\u00e1cil realizar pagos \u00fanicos o configurar pagos recurrentes.<\/p>\n<h3><strong>Pagar desde una cuenta segura<\/strong><\/h3>\n<ul>\n<li><span class=\"bold\"><strong>En l\u00ednea<\/strong><\/span> \u2013 Inicie sesi\u00f3n en su cuenta y seleccione <span class=\"bold\"><strong>Transferencia y pago &gt;<a href=\"https:\/\/www.soundcuonline.com\/dbank\/live\/app\/ql\/all\/b1c353e8ac\" rel=\"noopener\"><span class=\"underline\"> Transferencias y pagos de sonido<\/span><\/a><\/strong><\/span> para transferir su pago \u00fanico o configurar pagos recurrentes.<\/li>\n<li>Utilice la banca en l\u00ednea, m\u00f3vil o telef\u00f3nica para realizar transferencias de pago \u00fanicas o recurrentes.<\/li>\n<li><span class=\"underline\"><a href=\"https:\/\/www.soundcu.com\/es\/contact\/\">Cont\u00e1ctanos<\/a><\/span> De la forma que le resulte m\u00e1s conveniente, nosotros le transferiremos el pago.<\/li>\n<\/ul>\n<h3>Pagar desde otra instituci\u00f3n financiera<\/h3>\n<ul>\n<li><span class=\"bold\"><strong>En l\u00ednea<\/strong><\/span> \u2013 Inicia sesi\u00f3n en tu cuenta de Sound y selecciona:\n<ul>\n<li><span class=\"bold\"><strong>Transferencia y pago &gt; <a href=\"https:\/\/www.soundcuonline.com\/dbank\/live\/app\/ql\/all\/70990d0f94\" rel=\"noopener\"><span class=\"underline\">Transferencias externas<\/span><\/a><\/strong><\/span> para transferir dinero desde una cuenta que tienes en otra instituci\u00f3n financiera<\/li>\n<li><span class=\"bold\"><strong>Transferencia y pago &gt; <a href=\"https:\/\/www.soundcuonline.com\/dbank\/live\/app\/ql\/all\/5c3eee0e59\" rel=\"noopener\"><span class=\"underline\">Pagos externos<\/span><\/a><\/strong><\/span>\u00a0para configurar un pago utilizando su tarjeta de d\u00e9bito o una cuenta en otra instituci\u00f3n financiera.<\/li>\n<\/ul>\n<\/li>\n<li><span class=\"bold\"><strong>Dep\u00f3sito m\u00f3vil (cheque)<\/strong><\/span> \u2013 Descarga la aplicaci\u00f3n Sound y usa el Dep\u00f3sito M\u00f3vil para depositar un cheque en tu cuenta de ahorros o corriente, y luego transfiere el pago a tu pr\u00e9stamo.<\/li>\n<li><span class=\"bold\"><strong>Paga mediante ACH o tarjeta de d\u00e9bito.<\/strong><\/span> \u2013 Configurar un <a href=\"https:\/\/web.baconpay.com\/gate\/login?institutionId=60354d12-badc-4995-9b47-006167b7a40a\" rel=\"noopener\"><span class=\"underline\">pago acelerado del pr\u00e9stamo<\/span><\/a> a su tarjeta de cr\u00e9dito Sound, veh\u00edculo, personal, capital inmobiliario o hipoteca Express utilizando su tarjeta de d\u00e9bito o una cuenta en otra instituci\u00f3n financiera.<a href=\"https:\/\/www.soundcu.com\/es\/rates\/personal\/account-fees\/\"><span class=\"underline\">Honorarios<\/span><\/a> Aplicar. El monto m\u00e1ximo de pago es de $1,500)<\/li>\n<li><span class=\"bold\"><strong>Configurar pagos autom\u00e1ticos (pago ACH)<\/strong><\/span> \u2013 Completar el <a href=\"https:\/\/www.soundcu.com\/files\/ACH-Debit-Authorization.pdf\"><span class=\"underline\">Formulario de autorizaci\u00f3n de d\u00e9bito ACH<\/span><\/a>, lo que nos permite deducir autom\u00e1ticamente su pago cada mes de la cuenta que haya elegido.<\/li>\n<\/ul>\n<h3>Pago en persona (efectivo o cheque)<\/h3>\n<ul>\n<li>Visita un <a href=\"https:\/\/www.soundcu.com\/es\/branches\/\"><span class=\"underline\">Rama sana<\/span><\/a> Para realizar su pago en efectivo o con cheque.<\/li>\n<li>Visita un <a href=\"https:\/\/www.soundcu.com\/es\/branches\/\"><span class=\"underline\">Ubicaci\u00f3n de sucursal compartida de CO-OP<\/span><\/a> para realizar su pago.<\/li>\n<\/ul>\n<h3><strong>Pago por correo<\/strong><\/h3>\n<p>Por favor, incluya los \u00faltimos cuatro d\u00edgitos de su n\u00famero de cuenta y el n\u00famero de pr\u00e9stamo en su cheque.<\/p>\n<p>Sound Credit Union<br \/>\nApartado de correos 1595<br \/>\nTacoma, WA 98401<\/p>\n<h3><strong>Paga una hipoteca segura<\/strong><\/h3>\n<ul>\n<li><span class=\"bold\"><strong>En l\u00ednea<\/strong><\/span> \u2013 Realice pagos en l\u00ednea a trav\u00e9s de <span class=\"underline\"><a href=\"https:\/\/soundcu.loanadministration.com\/\" rel=\"noopener\">Centro de pago de hipotecas<\/a><\/span><\/li>\n<li><span class=\"bold\"><strong>Por correo (cheque)<\/strong><\/span> \u2013 Env\u00ede los pagos junto con su cup\u00f3n mensual desprendible a la siguiente direcci\u00f3n:<\/li>\n<\/ul>\n<p>Sound Credit Union<br \/>\nAtenci\u00f3n: Procesamiento de pagos<br \/>\nApartado de correos 11733<br \/>\nNewark, NJ 07101\u20104733<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/section>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__single-path-cta co-flex_row__next_row__back-to-top\" id=\"apply\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<svg class=\"co-sp_cta__svg\" width=\"488.512\" height=\"338.101\" viewbox=\"0 0 488.512 338.101\">\n\t\t\t<path class=\"co-sp_cta__svg--path_big\" d=\"M488.512,163.324C337.738,308.387,172.875,346.284,6.386,332.445c-12.895-1.072-2.726.507,0-169.121C7.666,83.681-1.682,4.826,3.448,4.309,177.337-13.221,346.255,19.454,488.512,163.324Z\"\/>\n\t\t\t<path class=\"co-sp_cta__svg--path_small\" d=\"M408.431,63.648c-126.358,121.572-278.108,50-408.431,0C129.644,19.327,291.966-54.138,408.431,63.648Z\" transform=\"translate(0 207.52)\" fill=\"#efc025\"\/>\n\t<\/svg>\n\t<div class=\"co-sp_cta\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Solicitar una l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC) de Sound es f\u00e1cil.<\/h2><div class=\"co-intro_text--intro\"><p>Solicitarlo en l\u00ednea es r\u00e1pido y sencillo, da el siguiente paso.<\/p>\n<\/div>\t\t<\/header>\n\t<a class=\"co-sp_cta--button gtm-button\" href=\"https:\/\/app.loanspq.com\/he\/HomeEquityLoan.aspx?lenderref=soundcu082521&#038;_ga=2.175010722.1490978376.1715007655-1124716528.1711565775&#038;_gl=1*1mlvo0l*_ga*MTEyNDcxNjUyOC4xNzExNTY1Nzc1*_ga_FR6440DWJ8*MTcxNTAyNTY2OC43MS4xLjE3MTUwMzI0NTkuNTQuMC4w\" target=\"_blank\" rel=\"noopener\">Solicita una l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria (HELOC).<\/a>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__back-to-top co-flex_row__next_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t<div class=\"co-back-to-top\">\t\n  <a class=\"co-back-to-top--link js-scroll_link\" href=\"#\" aria-label=\"\">\n\t\t<img\n\t\t\tclass=\"co-back-to-top--arrow\"\n\t\t\tsrc=\"https:\/\/www.soundcu.com\/wp-content\/themes\/soundcu-theme\/images\/back_top.svg\"\n\t\t\talt=\"Back to Top Button\"\n\t\t\twidth=\"18.07\"\n\t\t\theight=\"23.169\"\n\t\t\tloading=\"lazy\"\n\t\t>\n\t  Volver arriba  <\/a>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t<div class=\"small-text\">\n<p id=\"isPasted\">Todos los pr\u00e9stamos est\u00e1n sujetos a las pol\u00edticas de pr\u00e9stamos de Sound Credit Union. Es posible que se requiera verificaci\u00f3n de ingresos. Todos los pr\u00e9stamos est\u00e1n sujetos a aprobaci\u00f3n crediticia. Su tasa y l\u00edmite de cr\u00e9dito se determinar\u00e1n en funci\u00f3n de su solvencia crediticia individual, incluyendo ingresos, \u00edndice de endeudamiento y empleo. Debe tener 18 a\u00f1os de edad para calificar para un pr\u00e9stamo. Se requiere seguro de vivienda. Se aplica una comisi\u00f3n por cancelaci\u00f3n anticipada de $525 si el pr\u00e9stamo se cancela dentro de los primeros 24 meses. El costo estimado de la tasaci\u00f3n es de $850 y est\u00e1 sujeto a cambios. El monto m\u00e1ximo del pr\u00e9stamo est\u00e1 determinado por el capital acumulado en su vivienda. El capital acumulado en su vivienda se basa en el valor de tasaci\u00f3n. La TAE incluye solo intereses y ning\u00fan otro costo, y se basa en el valor de un \u00edndice. Este \u00edndice es la Tasa Preferencial publicada en el Wall Street Journal y podr\u00eda cambiar en cualquier momento. Sound utilizar\u00e1 el \u00cdndice m\u00e1s reciente disponible a partir de los 5 d\u00edas anteriores a la fecha de cualquier cambio en la Tasa de Porcentaje Anual. Para determinar la Tasa de Porcentaje Anual que se aplicar\u00e1 a su cuenta, se agregar\u00e1 un margen a su tasa de \u00cdndice actual. La l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria tiene una tasa variable y una TAE (correspondiente a la tasa peri\u00f3dica mensual), por lo que el pago m\u00ednimo puede variar. En ning\u00fan caso la Tasa de Porcentaje Anual ser\u00e1 inferior a 3.99% ni superior a la menor de 18% anuales o la tasa m\u00e1xima permitida por la ley aplicable. Puede solicitar hasta 90% del valor tasado. Para valores tasados entre 81% y 90%, puede solicitar hasta un m\u00e1ximo de $50,000 para pr\u00e9stamos y l\u00edneas de cr\u00e9dito con garant\u00eda hipotecaria. La tasa y la oferta est\u00e1n sujetas a cambios en cualquier momento. La propiedad hipotecada debe estar en Washington, Oreg\u00f3n o Idaho. Debe ser miembro de Sound Credit Union para participar.<\/p>\n<p>NMLS# 691150<br \/>\nIgualdad de oportunidades de vivienda.<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Financia tus proyectos de mejora del hogar, o pr\u00e1cticamente cualquier cosa, con una l\u00ednea de cr\u00e9dito con garant\u00eda hipotecaria de Sound. <a href=\"https:\/\/www.soundcu.com\/es\/heloc\/\">Contin\u00faa leyendo <span class=\"meta-nav\">\u2192<\/span><\/a><\/p>","protected":false},"author":10,"featured_media":11229,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-leadCapture.php","meta":{"_acf_changed":false,"content-type":"","_searchwp_excluded":"","footnotes":""},"county":[],"class_list":["post-13455","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/13455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/comments?post=13455"}],"version-history":[{"count":9,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/13455\/revisions"}],"predecessor-version":[{"id":17716,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/13455\/revisions\/17716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/media\/11229"}],"wp:attachment":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/media?parent=13455"}],"wp:term":[{"taxonomy":"county","embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/county?post=13455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}