{"id":2317,"date":"2023-08-14T18:12:37","date_gmt":"2023-08-15T01:12:37","guid":{"rendered":"https:\/\/www.soundcu.com\/personal\/debit-account\/"},"modified":"2026-01-14T10:08:09","modified_gmt":"2026-01-14T18:08:09","slug":"debit-account","status":"publish","type":"page","link":"https:\/\/www.soundcu.com\/es\/personal\/checking\/debit-account\/","title":{"rendered":"Cuenta de d\u00e9bito Sound Washington"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__white co-flex_row__page-hero co-flex_row__next_row__page-intro\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"co-page_hero  co-page_hero__has_image\" aria-label=\"Encabezado: Cuenta de d\u00e9bito Sound\">\n\t\t<div class=\"co-page_hero--inner\">\n\t\t\t<div class=\"prow items-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-page_hero--img_wrap pcol-lg:6 pcol-xl:7\">\n\t\t\t\t\t\t<div class=\"co-page_hero--mask\"><svg width=\"997.021\" height=\"609.682\" viewbox=\"0 0 997.021 609.682\"><defs><clippath id=\"svgPathHero\"><path d=\"M299.014.148H0V609.681H299.014c480.632.192,698.007-296.752,698.007-296.752C691.761-16.846,299.014.148,299.014.148\"\/><\/clippath><\/defs><image id=\"image_6a573ad8aa3fe\" xlink:href=\"https:\/\/www.soundcu.com\/files\/iStock-1271692625_997x610.jpg\" src=\"https:\/\/www.soundcu.com\/files\/iStock-1271692625_997x610.jpg\" clip-path=\"url(#svgPathHero)\"  alt=\"debit account\" \/><\/svg><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"co-page_hero--text pcol-lg:6 pcol-xl:5\">\n\t\t\t\t\t\t\t\t\t\t<h1 class=\"co-page_hero--title\" >Cuenta de d\u00e9bito s\u00f3lida<\/h1>\t\t\t\t\t<p class=\"co-page_hero--tagline\">Una cuenta sencilla para que puedas hacer las cosas.<\/p>\t\t\t\t\t\t<div class=\"co-page_hero--buttons\">\n\t\t\t\t\t\t\t<a class=\"co-page_hero--button gtm-button\" href=\"https:\/\/www.soundcu.com\/es\/speed-bump\/?url=https%3A%2F%2Fwww.soundcu.com%2Fopen-a-free-checking-account%2F&#038;prev=https%3A%2F%2Fwww.soundcu.com%2Fes%2Fpersonal%2Fchecking%2Fdebit-account%2F\"  >Abrir una cuenta<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__next_row_diff co-flex_row__page-intro co-flex_row__next_row__columns\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-page_intro\">\n\t\t<h2 class=\"co-page_intro--title\">Todo lo que necesitas, nada que no necesites.<\/h2><div class=\"co-page_intro--desc\"><p>Obt\u00e9n una cuenta de transacciones sencilla y sin comisiones, y una tarjeta Sound D\u00e9bito para acceder f\u00e1cilmente a tu dinero.<\/p>\n<\/div>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__next_row_diff co-flex_row__columns co-flex_row__next_row__cc-comparison-horizontal\" id=\"benefits\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-columns\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Beneficios de una cuenta de d\u00e9bito segura<\/h2>\t\t<\/header>\n\t\t\t\t<div class=\"co-columns--row prow prow-md:2 prow-lg:4 co-columns--row__icons justify-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconDollarSign\"\n\t\tviewbox=\"0 0 72.211 72.21\"\n\t\twidth=\"72.211\"\n\t\theight=\"72.21\"\n\t>\n\t\t<title>Dollar Sign<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-914.164 -626.336)\">\n\t\t\t<path d=\"M3716.695,2178.253l-5.983,5.983h.72a5.464,5.464,0,0,1,5.509,5.09,5.366,5.366,0,0,1-5.354,5.63h-3.574a5.366,5.366,0,0,1-5.359-5.36h-7.146c0,.292.013.581.033.868a12.519,12.519,0,0,0,10.687,11.509v.13a3.573,3.573,0,1,0,7.146,0v-.13a12.457,12.457,0,0,0,3.321-23.72\" transform=\"translate(-2760.671 -1518.222)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3702.923,2093.54l5.991-5.991h-.745a5.462,5.462,0,0,1-5.509-5.09,5.365,5.365,0,0,1,5.353-5.63h3.573a5.365,5.365,0,0,1,5.36,5.36h7.146c0-.284-.013-.565-.032-.844a12.516,12.516,0,0,0-10.688-11.533v-.13a3.573,3.573,0,0,0-7.146,0v.13a12.457,12.457,0,0,0-3.3,23.727\" transform=\"translate(-2760.67 -1428.682)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3720.04,2134.98l-7.558,7.559-5.991,5.991-6.515,6.516h6.246a5.324,5.324,0,0,0,.481,2.216l7.576-7.576,5.983-5.983,6.523-6.523h-6.271a5.324,5.324,0,0,0-.474-2.2\" transform=\"translate(-2764.238 -1483.671)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M3661.2,2030.745a4.183,4.183,0,0,0-7.446,3.812,27.742,27.742,0,0,1-42.579,33.839l4.876-4.877a12.427,12.427,0,0,1-2.4-6.539l-6.817,6.817a27.744,27.744,0,0,1,38.833-38.833l-5.891,5.89a12.439,12.439,0,0,1,2.4,6.548l5.967-5.967,2.127-2.127,1.36-1.36c3.19-4.81,1.035-7.931-.557-9.379a36.053,36.053,0,1,0,10.134,12.177\" transform=\"translate(-2678.772 -1384.739)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Evite las cuotas mensuales<\/h3><div class=\"co-columns--box_desc\"><p>Configure dep\u00f3sitos directos mensuales por un total de $500 o m\u00e1s y utilice estados de cuenta electr\u00f3nicos para evitar una tarifa de $3.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconStarTeamwork\"\n\t\tviewbox=\"0 0 72.388 72.388\"\n\t\twidth=\"72.388\"\n\t\theight=\"72.388\"\n\t>\n\t\t<title>Star Teamwork<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-197.847 -1006.406)\">\n\t\t\t<path d=\"M108.474,3918.9q-.515-1.218-1.115-2.389t-1.28-2.291q-.453-.747-.941-1.469-.732-1.083-1.538-2.11-.537-.683-1.106-1.34-.284-.329-.576-.65-.584-.643-1.2-1.257-.921-.922-1.907-1.775-.657-.569-1.341-1.107-1.026-.805-2.109-1.538a36.1,36.1,0,0,0-3.759-2.221q-.39-.2-.786-.391-1.582-.762-3.247-1.373t-3.4-1.057a35.991,35.991,0,0,0-3.533-.722,36.638,36.638,0,0,0-11.024,0,36,36,0,0,0-3.534.722q-1.734.446-3.4,1.057t-3.247,1.373q-.4.191-.786.391a36.106,36.106,0,0,0-3.759,2.221q-1.083.732-2.109,1.538-.684.538-1.341,1.107-.985.853-1.907,1.775-.614.614-1.2,1.257-.292.322-.577.65-.569.657-1.106,1.34-.806,1.026-1.538,2.11-.488.722-.941,1.469-.68,1.12-1.28,2.291t-1.115,2.389a36.194,36.194,0,1,0,66.7,0m-5.772,20.48q-.158.685-.349,1.356a28.192,28.192,0,0,1-4.148,8.636q-.395.554-.815,1.09t-.865,1.048q-.445.514-.913,1.005t-.96.96q-.983.938-2.053,1.779-.534.42-1.09.814t-1.129.763q-1.149.736-2.37,1.362-.61.313-1.237.6-.94.426-1.916.783-.65.238-1.315.445t-1.343.381q-.678.175-1.369.316t-1.394.249q-.7.108-1.416.18a28.694,28.694,0,0,1-2.894.146,28.3,28.3,0,0,1-28.3-28.3,28.667,28.667,0,0,1,.146-2.894q.073-.713.18-1.416t.249-1.394q.142-.691.316-1.369t.381-1.344q.207-.664.445-1.315.357-.975.783-1.916.283-.627.6-1.237.625-1.221,1.362-2.37.368-.574.763-1.129t.815-1.09q.84-1.069,1.779-2.053.469-.492.96-.96t1.005-.913q.514-.445,1.048-.865t1.09-.815a28.2,28.2,0,0,1,8.636-4.148q.671-.191,1.356-.349a28.593,28.593,0,0,1,9.285-.579q.713.073,1.416.18t1.394.249q.346.07.688.15,1.027.237,2.025.548.665.207,1.315.445.975.356,1.916.783.627.283,1.237.6,1.221.625,2.37,1.362.574.368,1.129.763t1.09.815q.535.42,1.048.865t1.005.913q.492.468.96.96t.913,1.005q.445.513.865,1.048t.815,1.09q.395.555.763,1.129.736,1.149,1.363,2.37.312.61.6,1.237.425.94.783,1.916.238.65.445,1.315.31,1,.548,2.025.079.342.15.688.142.69.249,1.394t.18,1.416a28.6,28.6,0,0,1-.579,9.286\" transform=\"translate(158.917 -2890.388)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M134.363,3959.94q-.107-.7-.249-1.394-.071-.346-.15-.688-.237-1.027-.548-2.025-.207-.664-.445-1.315-.357-.976-.783-1.916-.283-.627-.6-1.237-.625-1.221-1.363-2.37-.368-.574-.763-1.129t-.815-1.09q-.42-.535-.865-1.049t-.913-1.005q-.469-.491-.96-.96t-1.005-.913q-.513-.445-1.048-.865t-1.09-.815q-.555-.394-1.129-.763-1.148-.736-2.37-1.363-.61-.312-1.237-.6-.94-.425-1.916-.782-.65-.238-1.315-.445-1-.31-2.025-.548-.343-.079-.688-.15-.691-.141-1.394-.249t-1.416-.18a28.6,28.6,0,0,0-9.286.578q-.685.158-1.356.349A28.181,28.181,0,0,0,90,3941.169q-.555.395-1.09.815t-1.048.865q-.513.444-1.005.913t-.96.96q-.937.984-1.779,2.054-.42.534-.815,1.09T82.543,3949q-.736,1.148-1.362,2.37-.313.61-.6,1.237-.425.94-.783,1.916-.238.65-.445,1.315t-.381,1.343q-.174.678-.316,1.37t-.249,1.394q-.107.7-.18,1.416a28.608,28.608,0,0,0-.146,2.894,28.3,28.3,0,0,0,28.3,28.3,28.623,28.623,0,0,0,2.894-.146q.713-.073,1.416-.18t1.394-.249q.691-.141,1.369-.316t1.343-.382q.665-.207,1.315-.445.975-.357,1.916-.783.627-.283,1.237-.6,1.221-.625,2.37-1.362.574-.368,1.129-.762t1.09-.815q1.069-.84,2.053-1.778.492-.469.96-.96t.913-1.006q.445-.513.865-1.049t.815-1.089a28.187,28.187,0,0,0,4.148-8.635q.19-.672.349-1.357a28.6,28.6,0,0,0,.579-9.286q-.073-.713-.18-1.416m-9.1,23.183a26.69,26.69,0,1,1,7.817-18.872,26.515,26.515,0,0,1-7.817,18.872\" transform=\"translate(127.654 -2921.65)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M284.8,4194.67q-1.149.736-2.37,1.362,1.22-.625,2.37-1.362\" transform=\"translate(-35.508 -3128.226)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M325.551,4163.065c-.28.356-.569.707-.865,1.048.3-.342.585-.692.865-1.048\" transform=\"translate(-69.245 -3102.991)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M300.885,4186.843q-.534.42-1.09.814.555-.395,1.09-.814\" transform=\"translate(-49.371 -3121.977)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M329.793,4157.659q-.395.554-.815,1.089.42-.535.815-1.089\" transform=\"translate(-72.672 -3098.675)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M268.7,4204.388q-.94.425-1.916.783.975-.357,1.916-.783\" transform=\"translate(-23.016 -3135.986)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M353.951,4108.083q-.158.685-.349,1.356.191-.671.349-1.356\" transform=\"translate(-92.333 -3059.091)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M234.28,4215.175q-.7.107-1.417.18.714-.072,1.417-.18\" transform=\"translate(4.071 -3144.598)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M328.978,3989.675q.42.534.815,1.09-.395-.555-.815-1.09\" transform=\"translate(-72.672 -2964.549)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M336.806,4000.684q.736,1.148,1.362,2.37-.625-1.22-1.362-2.37\" transform=\"translate(-78.922 -2973.339)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M324.686,3984.474q.445.513.865,1.048-.42-.535-.865-1.048\" transform=\"translate(-69.245 -2960.396)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M305.2,3965.9q.535.42,1.048.865-.513-.445-1.048-.865\" transform=\"translate(-53.687 -2945.564)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M346.524,4018.581q.425.94.783,1.916-.357-.975-.783-1.916\" transform=\"translate(-86.681 -2987.628)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M282.434,3951.31q1.22.625,2.37,1.363-1.149-.736-2.37-1.363\" transform=\"translate(-35.509 -2933.916)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M299.795,3961.855q.555.395,1.09.815-.534-.42-1.09-.815\" transform=\"translate(-49.371 -2942.336)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M352.615,4034.613q.31,1,.548,2.025-.237-1.028-.548-2.025\" transform=\"translate(-91.545 -3000.429)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M266.788,3944.469q.975.357,1.916.783-.94-.425-1.916-.783\" transform=\"translate(-23.016 -2928.454)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M315.389,4174.214q.492-.469.96-.96-.469.491-.96.96\" transform=\"translate(-61.822 -3111.126)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M316.349,3975.683q-.469-.491-.96-.96.491.469.96.96\" transform=\"translate(-61.822 -2952.61)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M117.819,3974.723q-.492.469-.96.96.469-.491.96-.96\" transform=\"translate(96.694 -2952.61)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M254.942,4210.479q-.664.207-1.343.381.678-.175,1.343-.381\" transform=\"translate(-12.486 -3140.849)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M356.076,4048.07q.141.691.249,1.394-.107-.7-.249-1.394\" transform=\"translate(-94.308 -3011.174)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M357.31,4054.985q.107.7.18,1.417-.072-.714-.18-1.417\" transform=\"translate(-95.293 -3016.695)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M82.5,4035.955q.174-.679.381-1.343-.207.665-.381,1.343\" transform=\"translate(124.124 -3000.428)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M79.7,4049.463q.107-.7.249-1.394-.141.691-.249,1.394\" transform=\"translate(126.362 -3011.174)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M86.6,4020.5q.357-.975.783-1.916-.425.94-.783,1.916\" transform=\"translate(120.85 -2987.628)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M241.285,4213.94q-.691.141-1.394.249.7-.107,1.394-.249\" transform=\"translate(-1.541 -3143.613)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M93.446,4003.054q.625-1.22,1.362-2.37-.736,1.149-1.362,2.37\" transform=\"translate(115.388 -2973.339)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M250.219,3939.544q1.027.237,2.025.548-1-.31-2.025-.548\" transform=\"translate(-9.787 -2924.521)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M78.809,4056.4q.073-.713.18-1.417-.107.7-.18,1.417\" transform=\"translate(127.075 -3016.695)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M232.863,3936.673q.714.073,1.417.18-.7-.107-1.417-.18\" transform=\"translate(4.071 -2922.229)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M239.891,3937.566q.7.107,1.394.249-.691-.142-1.394-.249\" transform=\"translate(-1.541 -2922.942)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M180.064,3939.893q.671-.19,1.356-.349-.685.158-1.356.349\" transform=\"translate(46.228 -2924.521)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M131.811,3962.67q.535-.42,1.09-.815-.555.395-1.09.815\" transform=\"translate(84.756 -2942.336)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M126.61,3966.763q.513-.445,1.048-.865-.535.42-1.048.865\" transform=\"translate(88.908 -2945.564)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M103.991,3990.766q.395-.555.815-1.089-.42.534-.815,1.089\" transform=\"translate(106.969 -2964.55)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M150.9,3994.509l-5.72-11.59-5.72,11.59-12.79,1.859,9.255,9.021-2.185,12.739,11.44-6.014,11.44,6.014-2.185-12.739,9.255-9.021Z\" transform=\"translate(88.863 -2959.154)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Saldo m\u00ednimo cero<\/h3><div class=\"co-columns--box_desc\"><p>No existe un saldo m\u00ednimo para abrir o mantener la cuenta de d\u00e9bito Sound.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconBagWithDollarSign\"\n\t\tviewbox=\"0 0 69.832 71.004\"\n\t\twidth=\"69.832\"\n\t\theight=\"71.004\"\n\t>\n\t\t<title>Bag with Dollar Sign<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-535.355 -816.755)\">\n\t\t\t<path d=\"M1817.147,3031.256h17.97c.006.065.062.647.062.647.073,2.564-1.959,5.416-4.539,5.49l-10.072-.024,0,1.542h8.394l10.847-1.731.79-.456,6.26-3.579v-21.771c0-6.583-6.124-12.133-14.266-13.538v.711h-10.117v-.711c-8.141,1.405-14.266,6.956-14.266,13.538v27.486h1.991Zm11.157-13.711h-1.543a5.4,5.4,0,0,1-.771-10.742v-3.141h3.085v3.141a5.407,5.407,0,0,1,4.628,5.343h-3.085a2.316,2.316,0,0,0-2.313-2.314h-1.543a2.314,2.314,0,0,0,0,4.628h1.543a5.4,5.4,0,0,1,.771,10.742v3.141h-3.085V3025.2a5.407,5.407,0,0,1-4.627-5.343h3.085a2.316,2.316,0,0,0,2.314,2.314h1.543a2.314,2.314,0,0,0,0-4.627\" transform=\"translate(-1253.76 -2172.617)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M1883.26,2955.843l-7.032,1.542-7.032-1.542,2.806,6.09h8.453Z\" transform=\"translate(-1302.455 -2139.087)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M1849.024,3158.825l-1.161-1.154c-1.93-1.912-5.16-1.445-7.417.166l-3.377,1.931-6.26,3.578-.79.456-3,1.731h-16.242l0-1.542,10.072.023c2.581-.074,4.613-2.926,4.539-5.49,0,0-.056-.582-.062-.647h-17.969l-6.948,7.605h-4.462v13.879h11.718l25.288-9.318,16.2-11.064c-.045-.054-.085-.106-.135-.156\" transform=\"translate(-1243.973 -2299.24)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M1713.478,3207.63h15.557v-25.369h-15.557Zm8.033-7.375h2.927v3.085h-2.927Z\" transform=\"translate(-1178.123 -2319.871)\" fill=\"#00205b\"\/>\n\t\t\t<rect width=\"2.927\" height=\"3.085\" transform=\"translate(543.388 880.385)\" fill=\"#eaf4fe\"\/>\n\t\t\t<path d=\"M1889.1,2989.144v-3.085h-10.117v3.085Z\" transform=\"translate(-1310.274 -2163.213)\" fill=\"#00205b\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Pago anticipado<sup>1<\/sup><\/h3><div class=\"co-columns--box_desc\"><p>\u00a1Una exclusiva de Sound! Reciba su <a href=\"https:\/\/www.soundcu.com\/es\/blog\/direct-deposit-at-sound\/\">dep\u00f3sito directo<\/a> hasta un d\u00eda antes del d\u00eda de pago.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconCheck\"\n\t\tviewbox=\"0 0 86.07 53.073\"\n\t\twidth=\"86.07\"\n\t\theight=\"53.073\"\n\t>\n\t\t<title>Check<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-965.815 -438.603)\">\n\t\t\t<path d=\"M3849.207,1336.865Z\" transform=\"translate(-2883.392 -846.418)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3861.4,1184.742h71.2v-33.117L3911.4,1170h.383a1.229,1.229,0,0,1,0,2.457h-3.219l-6.3,5.462-8.281,2.5-2.41.729,2.307-4.954,1.741-3.739h-3.492a1.229,1.229,0,1,1,0-2.457h5.341l25.531-22.117H3861.4Zm25.8-4.915h-4.916a1.229,1.229,0,0,1,0-2.457h4.916a1.229,1.229,0,0,1,0,2.457m-7.373-9.83h7.373a1.229,1.229,0,0,1,0,2.457h-7.373a1.229,1.229,0,1,1,0-2.457m-13.516-13.516a1.229,1.229,0,0,1,1.229-1.229h9.83a1.229,1.229,0,0,1,1.229,1.229v9.83a1.229,1.229,0,0,1-1.229,1.229h-9.83a1.228,1.228,0,0,1-1.229-1.229Zm1.229,13.516h7.373a1.229,1.229,0,1,1,0,2.457h-7.373a1.229,1.229,0,0,1,0-2.457m0,7.372h9.83a1.229,1.229,0,1,1,0,2.457h-9.83a1.229,1.229,0,0,1,0-2.457\" transform=\"translate(-2893.127 -695.523)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M3849.64,1137.145h-.433v.935a1.224,1.224,0,0,1,.433-.935\" transform=\"translate(-2883.392 -686.952)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3887.013,1196.744h9.83a1.229,1.229,0,0,0,1.229-1.229v-9.83a1.229,1.229,0,0,0-1.229-1.229h-9.83a1.229,1.229,0,0,0-1.229,1.229v9.83a1.229,1.229,0,0,0,1.229,1.229m1.229-9.83h7.372v7.373h-7.372Z\" transform=\"translate(-2912.596 -724.728)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M3887.013,1260.07h7.373a1.229,1.229,0,0,0,0-2.457h-7.373a1.229,1.229,0,1,0,0,2.457\" transform=\"translate(-2912.596 -783.139)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3947.976,1260.07h7.372a1.229,1.229,0,0,0,0-2.457h-7.372a1.229,1.229,0,1,0,0,2.457\" transform=\"translate(-2961.272 -783.139)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M4007.71,1258.842a1.229,1.229,0,0,0,1.229,1.229h3.493l.668-1.435,1.18-1.022h-5.341a1.229,1.229,0,0,0-1.229,1.229\" transform=\"translate(-3009.948 -783.139)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M4099.821,1258.842a1.229,1.229,0,0,0-1.229-1.229h-.383l-2.837,2.457h3.219a1.229,1.229,0,0,0,1.229-1.229\" transform=\"translate(-3079.942 -783.139)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3887.013,1296.648h9.83a1.229,1.229,0,1,0,0-2.457h-9.83a1.229,1.229,0,1,0,0,2.457\" transform=\"translate(-2912.596 -812.345)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3965.084,1294.191h-4.915a1.229,1.229,0,1,0,0,2.457h4.915a1.229,1.229,0,1,0,0-2.457\" transform=\"translate(-2971.008 -812.345)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M3922.868,1141.89v33.118h-71.2v-36.862h61.59l2.837-2.457h-65.656a1.231,1.231,0,0,0-1.228,1.229v39.319a1.229,1.229,0,0,0,1.229,1.229H3924.1a1.229,1.229,0,0,0,1.229-1.229V1139.76Z\" transform=\"translate(-2883.392 -685.788)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M4241.632,1083.82l-2.989-3.45a2.1,2.1,0,0,0-2.965-.223l-2.137,1.851,1.918,2.214,1.914,2.21,1.917,2.214,2.137-1.852a2.1,2.1,0,0,0,.2-2.964\" transform=\"translate(-3190.262 -641.036)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M4059.99,1111.9l-5.535,4.8-2.837,2.457-25.531,22.117-1.18,1.023-.668,1.435-1.741,3.738c.033,1.285.075,2.928.1,4.226l8.281-2.5,6.3-5.462,2.836-2.458,21.209-18.372,2.458-2.129,2.276-1.971-2.977-3.436Z\" transform=\"translate(-3021.755 -666.792)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M4215.578,1093.05l-1.918-2.214-.11-.128-4.908,4.252,5.975,6.9,4.908-4.251-.114-.131-1.917-2.214Z\" transform=\"translate(-3170.381 -649.875)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M4013.46,1292.582c-.027-1.3-.069-2.942-.1-4.226l-2.307,4.954Z\" transform=\"translate(-3012.615 -807.686)\" fill=\"#efc025\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Giros postales y cheques bancarios gratuitos<\/h3><div class=\"co-columns--box_desc\"><p>Cada mes se incluyen tres (3) giros postales y cheques de caja gratuitos con la Cuenta de D\u00e9bito Sound.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__cc-comparison-horizontal co-flex_row__next_row__faqs\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-ccHorizontal\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">M\u00e1s funciones y beneficios<\/h2><div class=\"co-intro_text--intro\"><p>Descubre las ventajas disponibles con cada cuenta corriente de Sound Checking.<\/p>\n<\/div>\t\t<\/header>\n\t\t\t\t<div class=\"co-ccHorizontal--wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-ccHorizontal--card\">\n\t\t\t\t\t\t<div class=\"co-ccHorizontal--table prow\">\n\t\t\t\t\t\t\t<div class=\"co-ccHorizontal--col co-ccHorizontal--col_image pcol-md:4 pcol-lg:4\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"467\" src=\"https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-730x467.jpg\" class=\"co-ccHorizontal--card_img\" alt=\"Sound Contactless Debit Card\" srcset=\"https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-730x467.jpg 730w, https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-540x345.jpg 540w, https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-768x491.jpg 768w, https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-396x253.jpg 396w, https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-955x610.jpg 955w, https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit-75x48.jpg 75w, https:\/\/www.soundcu.com\/files\/Sound-Consumer-Debit.jpg 1050w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/div>\t\t\t\t\t\t\t<div class=\"co-ccHorizontal--col pcol-md:4 pcol-lg:5\">\n\t\t\t\t\t\t\t\t<h3 class=\"co-ccHorizontal--heading\">Cuenta de d\u00e9bito s\u00f3lida<\/h3>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Lo mejor si te interesa\u2026<\/span>\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Tarjeta de d\u00e9bito VISA sin contacto<\/li>\n<li>Un reembolso de la comisi\u00f3n por sobregiro cada a\u00f1o.<sup>2<\/sup><\/li>\n<li><a href=\"https:\/\/www.soundcu.com\/es\/personal\/online-banking\/\">Banca en l\u00ednea y pago de facturas<\/a><\/li>\n<li>Aplicaci\u00f3n m\u00f3vil<\/li>\n<li>Dep\u00f3sito m\u00f3vil y control de tarjetas<\/li>\n<li>Pago m\u00f3vil para Apple, Android y Samsung<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-ccHorizontal--col_inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-ccHorizontal--col_inner--content\">\n\t\t\t\t\t\t\t\t\t\t\t<span>Honorarios<\/span>\n\t\t\t\t\t\t\t\t\t\t\tConfigure dep\u00f3sitos directos mensuales por un total de $500 o m\u00e1s y utilice estados de cuenta electr\u00f3nicos para evitar una tarifa de $3.\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-ccHorizontal--col co-ccHorizontal--col_ctas  pcol-md:4 pcol-lg:3\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__faqs co-flex_row__next_row__multi-path-cta\" id=\"FAQs\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<section class=\"co-accords_section\" aria-label=\"Preguntas frecuentes, herramientas y recursos\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Preguntas frecuentes, herramientas y recursos<\/h2>\t\t<\/header>\n\t\t\t<div class=\"co-accordion\" data-animation=\"on\" data-multi-items=\"on\">\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4013\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfQu\u00e9 es una cuenta corriente?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>Una cuenta corriente es una cuenta bancaria que puedes usar para tus transacciones diarias. Esto incluye depositar cheques, retirar efectivo con tu tarjeta de d\u00e9bito y configurar dep\u00f3sitos directos de tu n\u00f3mina, seguridad social y m\u00e1s.<\/p>\n<p>Sound Credit Union ofrece cuentas corrientes. <a href=\"https:\/\/www.soundcu.com\/es\/personal\/checking\/\">M\u00e1s informaci\u00f3n \u00bb<\/a><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4014\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfC\u00f3mo puedo abrir una cuenta corriente?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>A <a href=\"https:\/\/www.soundcu.com\/es\/open-a-free-checking-account\/\">abrir una cuenta corriente<\/a> Deber\u00e1 completar una solicitud proporcionada y realizar un dep\u00f3sito inicial, si es necesario. Necesitar\u00e1 su n\u00famero de miembro (si ya es miembro) e informaci\u00f3n personal, incluyendo una identificaci\u00f3n oficial con foto. Las cuentas corrientes se pueden abrir en l\u00ednea o en cualquier <a href=\"https:\/\/www.soundcu.com\/es\/branches\/\">Ubicaci\u00f3n de la sucursal<\/a>. Si abre su cuenta <a href=\"https:\/\/www.soundcu.com\/es\/personal\/online-banking\/\">en l\u00ednea<\/a>, Tenga a mano su dispositivo m\u00f3vil y prep\u00e1rese para acceder a su cuenta de correo electr\u00f3nico.<\/p>\n<p><a href=\"https:\/\/www.soundcu.com\/es\/\">Sound Credit Union<\/a> Ofrece cuentas corrientes. <a href=\"https:\/\/www.soundcu.com\/es\/open-a-free-checking-account\/\">M\u00e1s informaci\u00f3n \u00bb<\/a><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"co-accordion--cta\"><p><a href=\"https:\/\/www.soundcu.com\/es\/support\/\">Obt\u00e9n m\u00e1s informaci\u00f3n en nuestra secci\u00f3n de soporte.<\/a><\/p>\n<\/div>\t<\/section>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__multi-path-cta co-flex_row__next_row__disclosures\" id=\"Open\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-mp_ctas\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Abre hoy mismo una cuenta de d\u00e9bito Sound Debit Account.<\/h2>\t\t<\/header>\n\t\t\t<div class=\"co-mp_ctas--list prow justify-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta pcol-lg:4\">\n\t\t\t\t\t<div class=\"co-mp_cta--title\">\n\t\t\t\t\t\tAbre tu cuenta en l\u00ednea\t\t\t\t\t<\/div>\n\t\t\t\t\t<a data-trigger-id=\"18040\" class=\"modal-trigger co-mp_cta--link\" href=\"#\">Abrir una cuenta<\/a>\t<div class=\"co-overlay with-sidebar\" data-trigger-id=\"18040\">\n\t\t<div class=\"co-overlay--inner\">\n\t\t\t\t\t<div class=\"co-overlay--content text-component\">\n\t\t\t\t<div class=\"co-overlay--content_inner\">\n\t\t\t\t\t<h2 class=\"co-overlay--title\">Abre una cuenta en Sound<\/h2><p>\u00bfEres nuevo en Sound o ya eres miembro?<\/p>\n\t\t\t\t\t\t<div class=\"co-overlay--cta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a data-trigger-id=\"18039\" class=\"modal-trigger co-overlay--cta_button\" href=\"#\">Soy nuevo<\/a>\t<div class=\"co-overlay with-sidebar\" data-trigger-id=\"18039\">\n\t\t<div class=\"co-overlay--inner\">\n\t\t\t\t\t<div class=\"co-overlay--content text-component\">\n\t\t\t\t<div class=\"co-overlay--content_inner\">\n\t\t\t\t\t<h2 class=\"co-overlay--title\">\u00a1Bienvenido!<\/h2><p>La membres\u00eda comienza con una cuenta de ahorros. Tambi\u00e9n puedes solicitar cuentas corrientes, certificados de dep\u00f3sito y m\u00e1s, todo en aproximadamente 5 minutos.<\/p>\n<p>Necesitar\u00e1s tener listo lo siguiente:<\/p>\n<ol>\n<li>Documento de identidad con fotograf\u00eda v\u00e1lido<\/li>\n<li>N\u00famero de Seguro Social (SSN) o n\u00famero de identificaci\u00f3n fiscal de EE. UU.<\/li>\n<li>Direcci\u00f3n postal f\u00edsica<\/li>\n<\/ol>\n\t\t\t\t\t\t<div class=\"co-overlay--cta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/account.soundcu.com\/\" rel=\"noopener\">Comience<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-overlay--sidebar text-component\">\n\t\t\t\t\t<h3>Gracias por su inter\u00e9s en el sonido.<\/h3>\n<p>Estamos aqu\u00ed para ayudarte de la manera que te resulte m\u00e1s f\u00e1cil.<\/p>\n<p><span class=\"co-button\"><a href=\"https:\/\/www.soundcu.com\/es\/contact\/\" target=\"_blank\" rel=\"noopener\">Cont\u00e1ctarnos<\/a><\/span><\/p>\n<hr \/>\n<div class=\"small-text\">\n<p><span class=\"co-button\"><a href=\"https:\/\/account.soundcu.com\/apptracker#\/\" rel=\"noopener\">Reanudar una aplicaci\u00f3n guardada<\/a><\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a data-trigger-id=\"19410\" class=\"modal-trigger co-overlay--cta_button\" href=\"#\">Ya eres miembro<\/a>\t<div class=\"co-overlay with-sidebar\" data-trigger-id=\"19410\">\n\t\t<div class=\"co-overlay--inner\">\n\t\t\t\t\t<div class=\"co-overlay--content text-component\">\n\t\t\t\t<div class=\"co-overlay--content_inner\">\n\t\t\t\t\t<h2 class=\"co-overlay--title\">\u00bfA\u00f1adir a tu membres\u00eda existente?<\/h2><p>\u00bfDesea agregar esta cuenta a su membres\u00eda existente o abrir una nueva?<\/p>\n<div class=\"small-text\">Para utilizar copropietarios diferentes, deber\u00e1 abrir una nueva membres\u00eda\/n\u00famero de miembro.<\/div>\n<p><\/br><\/p>\n\t\t\t\t\t\t<div class=\"co-overlay--cta\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/www.soundcuonline.com\/dbank\/live\/app\/ql\/all\/9a7212a45a\" rel=\"noopener\">Agregar cuenta a la membres\u00eda existente<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-overlay--cta__block\">\n\t\t\t\t\t\t\t\t\t<a class=\"co-overlay--cta_button\" href=\"https:\/\/account.soundcu.com\/\" rel=\"noopener\">Proceda con la nueva membres\u00eda<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-overlay--sidebar text-component\">\n\t\t\t\t\t<h3>Agradecemos su membres\u00eda.<\/h3>\n<p>Estamos aqu\u00ed para ayudarte de la manera que te resulte m\u00e1s f\u00e1cil.<\/p>\n<p><span class=\"co-button\"><a href=\"https:\/\/www.soundcu.com\/es\/contact\/\" target=\"_blank\" rel=\"noopener\">Cont\u00e1ctarnos<\/a><\/span><\/p>\n<hr \/>\n<div class=\"small-text\">\n<p><span class=\"co-button\"><a href=\"https:\/\/account.soundcu.com\/apptracker#\/\" rel=\"noopener\">Reanudar una aplicaci\u00f3n guardada<\/a><\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-overlay--sidebar text-component\">\n\t\t\t\t\t<h3>\u00a1Hola!<\/h3>\n<p>Estamos aqu\u00ed para ayudarte de la manera que te resulte m\u00e1s f\u00e1cil.<\/p>\n<p><span class=\"co-button\"><a href=\"https:\/\/www.soundcu.com\/es\/contact\/\" target=\"_blank\" rel=\"noopener\">Cont\u00e1ctarnos<\/a><\/span><\/p>\n<hr \/>\n<div class=\"small-text\">\n<p><span class=\"co-button\"><a href=\"https:\/\/account.soundcu.com\/apptracker#\/\" rel=\"noopener\">Reanudar una aplicaci\u00f3n guardada<\/a><\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta pcol-lg:4\">\n\t\t\t\t\t<div class=\"co-mp_cta--title\">\n\t\t\t\t\t\tVisita una sucursal local.\t\t\t\t\t<\/div>\n\t\t\t\t\t<a class=\"co-mp_cta--link gtm-button\" href=\"https:\/\/www.soundcu.com\/es\/speed-bump\/?url=https%3A%2F%2Fwww.soundcu.com%2Fbranches%2F&#038;prev=https%3A%2F%2Fwww.soundcu.com%2Fes%2Fpersonal%2Fchecking%2Fdebit-account%2F\">Encuentra una sucursal<\/a>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta pcol-lg:4\">\n\t\t\t\t\t<div class=\"co-mp_cta--title\">\n\t\t\t\t\t\tLl\u00e1menos\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"co-mp_cta--content\">\n\t\t\t\t\t\t\t<p><a href=\"tel:8005628130\">800.562.8130<\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t<div class=\"small-text\">\n<p>Todas las cuentas corrientes requieren membres\u00eda Sound. Debe cumplir con los requisitos para abrir una cuenta corriente. Las ofertas pueden cambiar en cualquier momento.<br \/>\n<strong>1. Cuenta de D\u00e9bito Sound<\/strong>No se aceptan cheques personales, pagos de cortes\u00eda, dep\u00f3sitos en cajeros autom\u00e1ticos ni transferencias bancarias.<br \/>\n<strong>2. Reembolso por sobregiro:<\/strong>\u00a0Previa solicitud, cada cuenta corriente puede reembolsar una comisi\u00f3n por sobregiro por a\u00f1o calendario.<\/p>\n<p>ASEGURADO FEDERALMENTE POR\u00a0<a href=\"https:\/\/mycreditunion.gov\/share-insurance-estimator-home\" target=\"_blank\" rel=\"noopener\">NCUA<\/a>.<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":2316,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_searchwp_excluded":"","footnotes":""},"county":[],"class_list":["post-2317","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/comments?post=2317"}],"version-history":[{"count":11,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2317\/revisions"}],"predecessor-version":[{"id":18113,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2317\/revisions\/18113"}],"up":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2316"}],"wp:attachment":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/media?parent=2317"}],"wp:term":[{"taxonomy":"county","embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/county?post=2317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}