{"id":2349,"date":"2023-08-14T18:12:40","date_gmt":"2023-08-15T01:12:40","guid":{"rendered":"https:\/\/www.soundcu.com\/personal\/insurance\/auto\/"},"modified":"2024-01-18T22:11:32","modified_gmt":"2024-01-19T06:11:32","slug":"auto","status":"publish","type":"page","link":"https:\/\/www.soundcu.com\/es\/personal\/insurance\/auto\/","title":{"rendered":"Seguro de autom\u00f3vil"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__blue co-flex_row__page-hero co-flex_row__next_row__page-intro\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"co-page_hero  co-page_hero__has_image\" aria-label=\"Encabezado: Seguro de autom\u00f3vil\">\n\t\t<div class=\"co-page_hero--inner\">\n\t\t\t<div class=\"prow items-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-page_hero--img_wrap pcol-lg:6 pcol-xl:7\">\n\t\t\t\t\t\t<div class=\"co-page_hero--mask\"><svg width=\"997.021\" height=\"609.682\" viewbox=\"0 0 997.021 609.682\"><defs><clippath id=\"svgPathHero\"><path d=\"M299.014.148H0V609.681H299.014c480.632.192,698.007-296.752,698.007-296.752C691.761-16.846,299.014.148,299.014.148\"\/><\/clippath><\/defs><image id=\"image_6a03d6c6113c4\" xlink:href=\"https:\/\/www.soundcu.com\/files\/auto-insurance.jpg\" src=\"https:\/\/www.soundcu.com\/files\/auto-insurance.jpg\" clip-path=\"url(#svgPathHero)\"  alt=\"Young person wearing a winter hat and hugging their dog in the back of their vehicle\" \/><\/svg><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"co-page_hero--text pcol-lg:6 pcol-xl:5\">\n\t\t\t\t\t\t\t\t\t\t\t<h1 class=\"co-page_hero--sup_heading\">\n\t\t\t\t\t\t\tServicios de seguros s\u00f3lidos\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"co-page_hero--title\" >Seguro de autom\u00f3vil<\/h2>\t\t\t\t\t<p class=\"co-page_hero--tagline\">Cobertura completa, desde el parachoques hasta el parachoques, y mucho m\u00e1s.<\/p>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__page-intro co-flex_row__next_row__sticky-nav\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-page_intro\">\n\t\t<div class=\"co-page_intro--desc\"><p>Nuestras soluciones integrales de seguros de autom\u00f3viles est\u00e1n dise\u00f1adas para protegerle a usted, a sus pasajeros y a su veh\u00edculo, brind\u00e1ndole la tranquilidad de poder conducir sin preocupaciones.<\/p>\n<\/div>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__sticky-nav co-flex_row__next_row__columns\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-sticky_nav_wrap is-active\" id=\"js-sticky_nav_wrap\">\n\t\t<nav\n\t\t\tclass=\"co-sticky_nav\"\n\t\t\tid=\"js-sticky_nav\"\n\t\t\taria-label=\"en la navegaci\u00f3n de anclaje de p\u00e1gina\"\n\t\t>\n\t\t\t<div class=\"co-sticky_nav--mobile\">\n\t\t\t\t<button\n\t\t\t\t\tclass=\"co-sticky_nav--toggle\"\n\t\t\t\t\tid=\"js-sticky_nav_toggle\"\n\t\t\t\t\taria-label=\"Abrir y cerrar men\u00fa de p\u00e1gina\"\n\t\t\t\t>Men\u00fa de p\u00e1gina<\/button>\n\t\t\t<\/div>\n\t\t\t<div\n\t\t\t\tclass=\"co-sticky_nav--row co-row\"\n\t\t\t\tid=\"js-sticky_nav_links\"\n\t\t\t>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#benefits\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\tBeneficios\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#faqs\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\tPreguntas frecuentes\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\thref=\"#quote\"\n\t\t\t\t\t\tclass=\"co-sticky_nav--link\t\t\t\t\t\t\tjs-sticky_nav_item\"\n\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\tSolicita un presupuesto\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/nav>\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__next_row_diff co-flex_row__columns co-flex_row__next_row__long-form-text\" id=\"benefits\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-columns\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<div class=\"co-intro_text--intro\"><p>Sound Insurance Services comprende la importancia de proteger su veh\u00edculo y garantizar su tranquilidad en la carretera.<\/p>\n<\/div>\t\t<\/header>\n\t\t\t\t<div class=\"co-columns--row prow prow-md:2 prow-lg:4 co-columns--row__icons justify-start\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconDocumentSignature\"\n\t\tviewbox=\"0 0 71.673 70.757\"\n\t\twidth=\"71.673\"\n\t\theight=\"70.757\"\n\t>\n\t\t<title>Document Signature<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-694.115 -1370.371)\">\n\t\t\t<path d=\"M2544.279,5758.327v2.948h29.912v-2.948\" transform=\"translate(-1841.475 -4376.725)\" fill=\"#fff\"\/>\n\t\t\t<path d=\"M2553.314,5787.582v2.949h23.668v-2.949\" transform=\"translate(-1848.689 -4400.083)\" fill=\"#fff\"\/>\n\t\t\t<path d=\"M2544.279,5816.837v2.948h19.593v-2.948\" transform=\"translate(-1841.475 -4423.443)\" fill=\"#fff\"\/>\n\t\t\t<path d=\"M2728.435,5785.135l-2.085-2.085-4.8,4.8-10.833,10.833,2.085,2.085,4.169,4.169,2.085,2.085,2.494-2.495,13.141-13.142-2.085-2.084Z\" transform=\"translate(-1974.365 -4396.465)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M2615.739,5873.054l-2.084-2.085-2.963,2.963-.678.692a114.229,114.229,0,0,0-12.137,14.015c-2.631,3.731-3.811,6.3-3.632,7.995l-2.479,2.479,2.084,2.084,2.429-2.428a3.247,3.247,0,0,0,.461.034c1.692,0,4.164-1.193,7.65-3.651a114.231,114.231,0,0,0,14.015-12.137l.681-.8,2.908-2.908-2.085-2.085Z\" transform=\"translate(-1879.389 -4466.664)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M2809.055,5759.329l-2.085-2.085a4.43,4.43,0,0,0-6.254,0l-2.084,2.085,2.085,2.084,4.169,4.169,2.085,2.085,2.084-2.085a4.421,4.421,0,0,0,0-6.253\" transform=\"translate(-2044.562 -4374.829)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M2730.559,5766.573l-4.17-4.169-2.085-2.084-3.127-3.127-3.759,3.759-11.876,11.876,2.085,2.084,9.791-9.792,3.759-3.759,1.043,1.042,2.085,2.085,4.169,4.169,2.085,2.085h0l2.085-2.085h0Z\" transform=\"translate(-1970.234 -4375.819)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M2702.455,5860.623h0l-2.085,2.085h0l2.085,2.085,4.169,4.169,2.084,2.085,2.085-2.085h0l-2.084-2.084-4.169-4.169Z\" transform=\"translate(-1966.105 -4458.403)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M2554.235,5702.6h-53.068v70.757h41.54l.04-.041v.041l11.488-11.487h-.041l.041-.041V5740.3l-2.494,2.495-2.085,2.084-2.908,2.909-.681.8a114.2,114.2,0,0,1-14.015,12.137c-3.486,2.458-5.958,3.651-7.65,3.651a3.17,3.17,0,0,1-.461-.035l-2.429,2.428-2.084-2.085,2.479-2.479c-.179-1.695,1-4.263,3.632-7.994a114.169,114.169,0,0,1,12.137-14.016l.678-.692,2.963-2.963h0l2.084-2.084h0l10.833-10.833v-2.085l-9.791,9.792-2.085-2.085,11.876-11.876Zm-11.488,59.27h10.3l-10.3,10.261Zm-13.3-33.3h-19.593v-2.948h19.593Zm5.9-5.9h-25.49v-2.948h25.49Zm4.422-5.9h-29.912v-2.948h29.912Z\" transform=\"translate(-1807.052 -4332.234)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h2 class=\"co-columns--box_headline\" >Cobertura personalizable<\/h2><div class=\"co-columns--box_desc\"><p>Ofrecemos una variedad de opciones de cobertura para satisfacer sus necesidades espec\u00edficas. Ya sea que necesite una cobertura b\u00e1sica de responsabilidad civil o una protecci\u00f3n integral, nosotros le brindamos la cobertura que necesita.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconCalculator\"\n\t\tviewbox=\"0 0 44.452 69.671\"\n\t\twidth=\"44.452\"\n\t\theight=\"69.671\"\n\t>\n\t\t<title>Calculator<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-869.798 -431.253)\">\n\t\t<path d=\"M3414.592,1107.5H3409.3v4.468h-29.354V1107.5h-4.139a3,3,0,0,0-2.993,2.993v50.719a3,3,0,0,0,2.993,2.993h38.467a3,3,0,0,0,2.992-2.993v-50.719a3.386,3.386,0,0,0-2.263-2.884,2.262,2.262,0,0,0-.413-.109m-27.158,45.011h-5.47v3.231h-2.993v-6.224h8.463Zm0-8.21h-5.47v3.231h-2.993v-6.224h8.463Zm0-8.21h-5.47v3.231h-2.993V1133.1h8.463Zm11.449,16.421h-5.471v3.231h-2.992v-6.224h8.463Zm0-8.21h-5.471v3.231h-2.992v-6.224h8.463Zm0-8.21h-5.471v3.231h-2.992V1133.1h8.463Zm11.971,16.421h-5.47v3.231h-2.992v-6.224h8.462Zm0-8.21h-5.47v3.231h-2.992v-6.224h8.462Zm0-8.21h-5.47v3.231h-2.992V1133.1h8.462Zm.941-8.687h-33.837v-8.957h33.837Zm1-12.433h-36.325v-2.993h36.325Z\" transform=\"translate(-2503.018 -663.282)\" fill=\"#1f79af\"\/>\n\t\t<rect width=\"36.325\" height=\"2.993\" transform=\"translate(873.447 448.697)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3408.2,1043.17V1060.6h29.354V1043.17Z\" transform=\"translate(-2531.273 -611.918)\" fill=\"#efc025\"\/>\n\t\t<path d=\"M3403.353,1240.729h2.993V1237.5h5.47v-2.993h-8.463Z\" transform=\"translate(-2527.4 -764.689)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3460.154,1240.729h2.992V1237.5h5.47v-2.993h-8.463Z\" transform=\"translate(-2572.753 -764.689)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3519.548,1240.729h2.993V1237.5h5.47v-2.993h-8.463Z\" transform=\"translate(-2620.176 -764.689)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3403.353,1281.464h2.993v-3.231h5.47v-2.993h-8.463Z\" transform=\"translate(-2527.4 -797.213)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3460.154,1281.464h2.992v-3.231h5.47v-2.993h-8.463Z\" transform=\"translate(-2572.753 -797.213)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3519.548,1281.464h2.993v-3.231h5.47v-2.993h-8.463Z\" transform=\"translate(-2620.176 -797.213)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3403.353,1322.2h2.993v-3.231h5.47v-2.993h-8.463Z\" transform=\"translate(-2527.4 -829.74)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3460.154,1322.2h2.992v-3.231h5.47v-2.993h-8.463Z\" transform=\"translate(-2572.753 -829.74)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3519.548,1322.2h2.993v-3.231h5.47v-2.993h-8.463Z\" transform=\"translate(-2620.176 -829.74)\" fill=\"#00205b\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h2 class=\"co-columns--box_headline\" >Primas competitivas<\/h2><div class=\"co-columns--box_desc\"><p>Disfrute de primas asequibles sin sacrificar la calidad de la cobertura. Nuestro objetivo es ofrecerle soluciones econ\u00f3micas que se ajusten a su presupuesto.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconStarTeamwork\"\n\t\tviewbox=\"0 0 72.388 72.388\"\n\t\twidth=\"72.388\"\n\t\theight=\"72.388\"\n\t>\n\t\t<title>Star Teamwork<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-197.847 -1006.406)\">\n\t\t\t<path d=\"M108.474,3918.9q-.515-1.218-1.115-2.389t-1.28-2.291q-.453-.747-.941-1.469-.732-1.083-1.538-2.11-.537-.683-1.106-1.34-.284-.329-.576-.65-.584-.643-1.2-1.257-.921-.922-1.907-1.775-.657-.569-1.341-1.107-1.026-.805-2.109-1.538a36.1,36.1,0,0,0-3.759-2.221q-.39-.2-.786-.391-1.582-.762-3.247-1.373t-3.4-1.057a35.991,35.991,0,0,0-3.533-.722,36.638,36.638,0,0,0-11.024,0,36,36,0,0,0-3.534.722q-1.734.446-3.4,1.057t-3.247,1.373q-.4.191-.786.391a36.106,36.106,0,0,0-3.759,2.221q-1.083.732-2.109,1.538-.684.538-1.341,1.107-.985.853-1.907,1.775-.614.614-1.2,1.257-.292.322-.577.65-.569.657-1.106,1.34-.806,1.026-1.538,2.11-.488.722-.941,1.469-.68,1.12-1.28,2.291t-1.115,2.389a36.194,36.194,0,1,0,66.7,0m-5.772,20.48q-.158.685-.349,1.356a28.192,28.192,0,0,1-4.148,8.636q-.395.554-.815,1.09t-.865,1.048q-.445.514-.913,1.005t-.96.96q-.983.938-2.053,1.779-.534.42-1.09.814t-1.129.763q-1.149.736-2.37,1.362-.61.313-1.237.6-.94.426-1.916.783-.65.238-1.315.445t-1.343.381q-.678.175-1.369.316t-1.394.249q-.7.108-1.416.18a28.694,28.694,0,0,1-2.894.146,28.3,28.3,0,0,1-28.3-28.3,28.667,28.667,0,0,1,.146-2.894q.073-.713.18-1.416t.249-1.394q.142-.691.316-1.369t.381-1.344q.207-.664.445-1.315.357-.975.783-1.916.283-.627.6-1.237.625-1.221,1.362-2.37.368-.574.763-1.129t.815-1.09q.84-1.069,1.779-2.053.469-.492.96-.96t1.005-.913q.514-.445,1.048-.865t1.09-.815a28.2,28.2,0,0,1,8.636-4.148q.671-.191,1.356-.349a28.593,28.593,0,0,1,9.285-.579q.713.073,1.416.18t1.394.249q.346.07.688.15,1.027.237,2.025.548.665.207,1.315.445.975.356,1.916.783.627.283,1.237.6,1.221.625,2.37,1.362.574.368,1.129.763t1.09.815q.535.42,1.048.865t1.005.913q.492.468.96.96t.913,1.005q.445.513.865,1.048t.815,1.09q.395.555.763,1.129.736,1.149,1.363,2.37.312.61.6,1.237.425.94.783,1.916.238.65.445,1.315.31,1,.548,2.025.079.342.15.688.142.69.249,1.394t.18,1.416a28.6,28.6,0,0,1-.579,9.286\" transform=\"translate(158.917 -2890.388)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M134.363,3959.94q-.107-.7-.249-1.394-.071-.346-.15-.688-.237-1.027-.548-2.025-.207-.664-.445-1.315-.357-.976-.783-1.916-.283-.627-.6-1.237-.625-1.221-1.363-2.37-.368-.574-.763-1.129t-.815-1.09q-.42-.535-.865-1.049t-.913-1.005q-.469-.491-.96-.96t-1.005-.913q-.513-.445-1.048-.865t-1.09-.815q-.555-.394-1.129-.763-1.148-.736-2.37-1.363-.61-.312-1.237-.6-.94-.425-1.916-.782-.65-.238-1.315-.445-1-.31-2.025-.548-.343-.079-.688-.15-.691-.141-1.394-.249t-1.416-.18a28.6,28.6,0,0,0-9.286.578q-.685.158-1.356.349A28.181,28.181,0,0,0,90,3941.169q-.555.395-1.09.815t-1.048.865q-.513.444-1.005.913t-.96.96q-.937.984-1.779,2.054-.42.534-.815,1.09T82.543,3949q-.736,1.148-1.362,2.37-.313.61-.6,1.237-.425.94-.783,1.916-.238.65-.445,1.315t-.381,1.343q-.174.678-.316,1.37t-.249,1.394q-.107.7-.18,1.416a28.608,28.608,0,0,0-.146,2.894,28.3,28.3,0,0,0,28.3,28.3,28.623,28.623,0,0,0,2.894-.146q.713-.073,1.416-.18t1.394-.249q.691-.141,1.369-.316t1.343-.382q.665-.207,1.315-.445.975-.357,1.916-.783.627-.283,1.237-.6,1.221-.625,2.37-1.362.574-.368,1.129-.762t1.09-.815q1.069-.84,2.053-1.778.492-.469.96-.96t.913-1.006q.445-.513.865-1.049t.815-1.089a28.187,28.187,0,0,0,4.148-8.635q.19-.672.349-1.357a28.6,28.6,0,0,0,.579-9.286q-.073-.713-.18-1.416m-9.1,23.183a26.69,26.69,0,1,1,7.817-18.872,26.515,26.515,0,0,1-7.817,18.872\" transform=\"translate(127.654 -2921.65)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M284.8,4194.67q-1.149.736-2.37,1.362,1.22-.625,2.37-1.362\" transform=\"translate(-35.508 -3128.226)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M325.551,4163.065c-.28.356-.569.707-.865,1.048.3-.342.585-.692.865-1.048\" transform=\"translate(-69.245 -3102.991)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M300.885,4186.843q-.534.42-1.09.814.555-.395,1.09-.814\" transform=\"translate(-49.371 -3121.977)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M329.793,4157.659q-.395.554-.815,1.089.42-.535.815-1.089\" transform=\"translate(-72.672 -3098.675)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M268.7,4204.388q-.94.425-1.916.783.975-.357,1.916-.783\" transform=\"translate(-23.016 -3135.986)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M353.951,4108.083q-.158.685-.349,1.356.191-.671.349-1.356\" transform=\"translate(-92.333 -3059.091)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M234.28,4215.175q-.7.107-1.417.18.714-.072,1.417-.18\" transform=\"translate(4.071 -3144.598)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M328.978,3989.675q.42.534.815,1.09-.395-.555-.815-1.09\" transform=\"translate(-72.672 -2964.549)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M336.806,4000.684q.736,1.148,1.362,2.37-.625-1.22-1.362-2.37\" transform=\"translate(-78.922 -2973.339)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M324.686,3984.474q.445.513.865,1.048-.42-.535-.865-1.048\" transform=\"translate(-69.245 -2960.396)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M305.2,3965.9q.535.42,1.048.865-.513-.445-1.048-.865\" transform=\"translate(-53.687 -2945.564)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M346.524,4018.581q.425.94.783,1.916-.357-.975-.783-1.916\" transform=\"translate(-86.681 -2987.628)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M282.434,3951.31q1.22.625,2.37,1.363-1.149-.736-2.37-1.363\" transform=\"translate(-35.509 -2933.916)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M299.795,3961.855q.555.395,1.09.815-.534-.42-1.09-.815\" transform=\"translate(-49.371 -2942.336)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M352.615,4034.613q.31,1,.548,2.025-.237-1.028-.548-2.025\" transform=\"translate(-91.545 -3000.429)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M266.788,3944.469q.975.357,1.916.783-.94-.425-1.916-.783\" transform=\"translate(-23.016 -2928.454)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M315.389,4174.214q.492-.469.96-.96-.469.491-.96.96\" transform=\"translate(-61.822 -3111.126)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M316.349,3975.683q-.469-.491-.96-.96.491.469.96.96\" transform=\"translate(-61.822 -2952.61)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M117.819,3974.723q-.492.469-.96.96.469-.491.96-.96\" transform=\"translate(96.694 -2952.61)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M254.942,4210.479q-.664.207-1.343.381.678-.175,1.343-.381\" transform=\"translate(-12.486 -3140.849)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M356.076,4048.07q.141.691.249,1.394-.107-.7-.249-1.394\" transform=\"translate(-94.308 -3011.174)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M357.31,4054.985q.107.7.18,1.417-.072-.714-.18-1.417\" transform=\"translate(-95.293 -3016.695)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M82.5,4035.955q.174-.679.381-1.343-.207.665-.381,1.343\" transform=\"translate(124.124 -3000.428)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M79.7,4049.463q.107-.7.249-1.394-.141.691-.249,1.394\" transform=\"translate(126.362 -3011.174)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M86.6,4020.5q.357-.975.783-1.916-.425.94-.783,1.916\" transform=\"translate(120.85 -2987.628)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M241.285,4213.94q-.691.141-1.394.249.7-.107,1.394-.249\" transform=\"translate(-1.541 -3143.613)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M93.446,4003.054q.625-1.22,1.362-2.37-.736,1.149-1.362,2.37\" transform=\"translate(115.388 -2973.339)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M250.219,3939.544q1.027.237,2.025.548-1-.31-2.025-.548\" transform=\"translate(-9.787 -2924.521)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M78.809,4056.4q.073-.713.18-1.417-.107.7-.18,1.417\" transform=\"translate(127.075 -3016.695)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M232.863,3936.673q.714.073,1.417.18-.7-.107-1.417-.18\" transform=\"translate(4.071 -2922.229)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M239.891,3937.566q.7.107,1.394.249-.691-.142-1.394-.249\" transform=\"translate(-1.541 -2922.942)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M180.064,3939.893q.671-.19,1.356-.349-.685.158-1.356.349\" transform=\"translate(46.228 -2924.521)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M131.811,3962.67q.535-.42,1.09-.815-.555.395-1.09.815\" transform=\"translate(84.756 -2942.336)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M126.61,3966.763q.513-.445,1.048-.865-.535.42-1.048.865\" transform=\"translate(88.908 -2945.564)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M103.991,3990.766q.395-.555.815-1.089-.42.534-.815,1.089\" transform=\"translate(106.969 -2964.55)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M150.9,3994.509l-5.72-11.59-5.72,11.59-12.79,1.859,9.255,9.021-2.185,12.739,11.44-6.014,11.44,6.014-2.185-12.739,9.255-9.021Z\" transform=\"translate(88.863 -2959.154)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h2 class=\"co-columns--box_headline\" >Servicio al cliente superior<\/h2><div class=\"co-columns--box_desc\"><p>Nuestro equipo especializado se compromete a brindar un servicio y soporte excepcionales. Estamos aqu\u00ed para responder sus preguntas, ayudarle con sus reclamaciones y guiarle durante todo el proceso de su seguro.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconTimer\"\n\t\tviewbox=\"0 0 55.358 69.183\"\n\t\twidth=\"55.358\"\n\t\theight=\"69.183\"\n\t>\n\t\t<title>Timer<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-870.336 -222.221)\">\n\t\t<path d=\"M3504.836,200.839a2.306,2.306,0,1,0,.844,3.15,2.293,2.293,0,0,0-.844-3.15\" transform=\"translate(-2605.667 60.887)\" fill=\"#1f79af\"\/>\n\t\t<path d=\"M3512.6,349.306h0\" transform=\"translate(-2614.626 -57.902)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3512.817,120.456h0\" transform=\"translate(-2614.801 124.822)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3524.258,131.866s0,0,0-.007v.015s0,0,0-.007\" transform=\"translate(-2623.937 115.717)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3534.736,99.693l-.049-.009-.038-.007.2.04-.108-.024\" transform=\"translate(-2632.233 141.413)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3538.114,100.414l.2.045-.2-.045\" transform=\"translate(-2635 140.824)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3375.555,216.594a27.386,27.386,0,0,0,2,9.41h0a27.384,27.384,0,0,1-2-9.408\" transform=\"translate(-2505.205 48.061)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3375.488,213.25c0,.05,0,.1,0,.151,0-.05,0-.1,0-.151\" transform=\"translate(-2505.151 50.73)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3386.016,264.6v0c.03.072.06.144.091.216h0l-.089-.212\" transform=\"translate(-2513.556 9.731)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3375.506,214.125c0,.166,0,.332.01.5-.005-.166-.007-.332-.01-.5\" transform=\"translate(-2505.166 50.032)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3512.819,349.3h0\" transform=\"translate(-2614.803 -57.902)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3608.428,310.515l-.011.01.011-.01\" transform=\"translate(-2691.133 -26.931)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3609.958,307.912l-.019.02q.142-.142.283-.285l-.012.011c-.083.085-.167.17-.252.254\" transform=\"translate(-2692.348 -24.64)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3611.465,274.113l-.019.02a27.373,27.373,0,0,0,5.587-8.432v0a27.377,27.377,0,0,1-5.566,8.41\" transform=\"translate(-2693.552 8.851)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3639.655,263.55l0,0,.1-.245h0l-.1.239\" transform=\"translate(-2716.074 10.761)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3650.135,212.382c0-.136,0-.273,0-.409,0,.136,0,.273,0,.409\" transform=\"translate(-2724.443 51.75)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3563.6,339.028c-.1.043-.209.083-.314.124.1-.041.209-.082.314-.124\" transform=\"translate(-2655.098 -49.697)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3608.407,113.37l.014.014Z\" transform=\"translate(-2691.125 130.479)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3417.168,310.516l-.021-.021.021.021\" transform=\"translate(-2538.414 -26.915)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3641.844,217.828c-.006.044-.013.087-.02.131q-.033.207-.069.415c-.022.128-.044.256-.068.383-.011.056-.021.112-.032.168a27.351,27.351,0,0,1-.823,3.216l-.031.1c-.051.158-.1.315-.158.472q-.062.178-.126.356c-.022.062-.044.125-.068.187q-.145.4-.3.785h0a27.381,27.381,0,0,0,2.011-9.915,27.587,27.587,0,0,1-.318,3.709\" transform=\"translate(-2716.47 50.037)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3414.57,307.921c-.1-.1-.2-.2-.293-.3.1.1.195.2.293.3\" transform=\"translate(-2536.122 -24.623)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3415.781,113.746c.089-.089.178-.179.269-.267-.09.088-.18.178-.269.267\" transform=\"translate(-2537.324 130.392)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3375.494,210.357c0-.136,0-.272,0-.408,0,.136,0,.272,0,.408\" transform=\"translate(-2505.156 53.366)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3650.134,209.852c0-.008,0-.016,0-.024,0,.008,0,.016,0,.024\" transform=\"translate(-2724.442 53.463)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3639.657,159.429q.05.121.1.243c-.032-.081-.066-.162-.1-.243\" transform=\"translate(-2716.077 93.704)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3617.024,124.833a27.381,27.381,0,0,0-5.588-8.434,27.855,27.855,0,0,1,4.085,5.429,28.233,28.233,0,0,1,1.5,3\" transform=\"translate(-2693.543 128.061)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3459.925,338.665l.181.076-.181-.076\" transform=\"translate(-2572.571 -49.407)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3609.93,114.876c.1.1.192.191.286.289-.094-.1-.19-.193-.286-.289\" transform=\"translate(-2692.341 129.277)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3375.562,169.258q.045-.676.123-1.352c.039-.335.086-.669.137-1,.008-.055.017-.11.025-.165.02-.127.041-.253.063-.38s.048-.278.074-.416c.008-.045.017-.089.026-.134a27.4,27.4,0,0,1,.83-3.244l.021-.064q.081-.252.168-.5c.038-.11.077-.219.116-.328.026-.071.051-.142.077-.213.094-.257.191-.512.292-.764a27.355,27.355,0,0,0-2.007,9.9q.005-.329.02-.659t.036-.676\" transform=\"translate(-2505.166 92.696)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3386.041,158.5c.028-.066.055-.133.083-.2-.028.066-.056.132-.083.2\" transform=\"translate(-2513.577 94.604)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3625.848,194.29c.006.039.012.077.018.117-.006-.039-.012-.078-.018-.117\" transform=\"translate(-2705.051 65.869)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3620.168,172.433c.019.052.038.1.056.155-.019-.052-.037-.1-.056-.155\" transform=\"translate(-2700.516 83.321)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3620.967,174.676q.068.2.132.394-.064-.2-.132-.394\" transform=\"translate(-2701.154 81.53)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3625.281,190.995c.021.109.04.218.058.327q-.028-.164-.058-.327\" transform=\"translate(-2704.598 68.5)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3399.689,228.99l.023.152c-.008-.051-.015-.1-.023-.152\" transform=\"translate(-2524.475 38.163)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3529.868,325.014l.139-.021-.139.021\" transform=\"translate(-2628.416 -38.49)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3532.119,324.487l.348-.062c-.116.022-.232.042-.348.062\" transform=\"translate(-2630.213 -38.037)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3405.145,250.615l.07.193c-.023-.064-.047-.129-.07-.193\" transform=\"translate(-2528.831 20.896)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3403.977,247.194c.047.144.094.288.144.431-.049-.143-.1-.286-.144-.431\" transform=\"translate(-2527.898 23.628)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3551.51,319.373l.178-.064-.178.064\" transform=\"translate(-2645.696 -33.952)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3548.078,320.247c.14-.046.28-.092.419-.14-.139.048-.279.095-.419.14\" transform=\"translate(-2642.956 -34.589)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3536.015,321.206q-.806.216-1.619.373a22.885,22.885,0,0,0,2.7-.692q-.537.172-1.086.319\" transform=\"translate(-2632.031 -35.212)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3491.368,99.185q-.294.05-.585.107c.2-.038.39-.073.585-.107\" transform=\"translate(-2597.208 141.805)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3475.907,103.159q-.2.066-.405.136c.135-.046.27-.092.405-.136\" transform=\"translate(-2585.007 138.632)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3622.434,179.7a22.846,22.846,0,0,0-.686-2.683q.17.533.317,1.077.215.8.37,1.606\" transform=\"translate(-2701.777 79.658)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3495.246,98.763l-.285.042.285-.042\" transform=\"translate(-2600.544 142.142)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3400.839,235.144q-.216-.81-.374-1.625a22.893,22.893,0,0,0,.694,2.715q-.173-.539-.321-1.09\" transform=\"translate(-2525.095 34.547)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3473.427,104.33l-.168.061.168-.061\" transform=\"translate(-2583.217 137.698)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3400.053,231.242q.031.18.064.36c-.023-.12-.044-.24-.064-.36\" transform=\"translate(-2524.765 36.365)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3478.928,100.1q.739-.2,1.482-.346a22.891,22.891,0,0,0-2.563.664q.535-.171,1.081-.318\" transform=\"translate(-2586.88 141.349)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3385.472,263.274h0c.036.089.073.177.109.266v0c-.038-.09-.074-.18-.111-.27\" transform=\"translate(-2513.123 10.789)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3387.967,268.678a27.965,27.965,0,0,1-1.506-3.012h0a27.363,27.363,0,0,0,5.6,8.445,27.836,27.836,0,0,1-4.09-5.434\" transform=\"translate(-2513.913 8.879)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3375.5,214h0c0,.008,0,.017,0,.026,0-.009,0-.017,0-.026\" transform=\"translate(-2505.164 50.133)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3472.429,341.554a27.631,27.631,0,0,1-3.939-.293c-.133-.019-.265-.038-.4-.059l-.271-.045q-.377-.064-.751-.137l-.012,0a27.362,27.362,0,0,1-3.1-.8l-.042-.014q-.264-.086-.525-.176l-.3-.106-.241-.087q-.309-.113-.615-.234a27.355,27.355,0,0,0,10.151,1.957Z\" transform=\"translate(-2574.413 -50.152)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3639.158,264.745v0c.033-.079.066-.158.1-.237l0,0c-.033.081-.067.163-.1.243\" transform=\"translate(-2715.678 9.808)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3611.336,307.436l-.052.054.012-.012.021-.022.019-.02\" transform=\"translate(-2693.422 -24.472)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3568.852,313.377q-.8.461-1.62.867-.772.382-1.562.711a27.378,27.378,0,0,0,8.615-5.667l.011-.01c.1-.1.2-.195.3-.293l.019-.02a27.81,27.81,0,0,1-5.76,4.413\" transform=\"translate(-2657.002 -25.692)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3507.2,265.184l-.179.065-.273.1c-.139.049-.279.095-.419.14l-.053.017a22.94,22.94,0,0,1-2.7.692l-.111.021c-.116.021-.231.042-.348.062s-.209.036-.315.053l-.138.021a23.164,23.164,0,0,1-6.868,0,23.062,23.062,0,0,0,25.068-14.83,23.179,23.179,0,0,1-13.659,13.663\" transform=\"translate(-2601.208 20.173)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3530.676,98.973l.257.043-.257-.043\" transform=\"translate(-2629.062 141.975)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3399.813,206.363c-.024-.064-.047-.129-.07-.193-.031-.086-.062-.172-.091-.259-.049-.143-.1-.287-.145-.431,0-.014-.009-.028-.013-.042a22.759,22.759,0,0,1-.694-2.714l-.02-.1c-.022-.12-.043-.24-.064-.36-.017-.1-.034-.2-.05-.3-.008-.05-.016-.1-.023-.152a23.167,23.167,0,0,1,0-6.861,23.062,23.062,0,0,0,14.819,25.063,23.177,23.177,0,0,1-13.649-13.65\" transform=\"translate(-2523.43 65.341)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3400.37,190.521c.006-.034.013-.068.019-.1-.007.034-.013.068-.019.1\" transform=\"translate(-2525.019 68.96)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3399.8,193c.016-.1.034-.2.051-.3-.018.1-.034.2-.051.3\" transform=\"translate(-2524.565 67.141)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3491.373,324.344l-.1-.019.1.019\" transform=\"translate(-2597.601 -37.957)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3474.443,319.741l-.255-.09.255.09\" transform=\"translate(-2583.958 -34.225)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3404.689,173.579q.045-.132.093-.263c-.031.087-.063.175-.093.263\" transform=\"translate(-2528.467 82.616)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3477.65,320.831l-.037-.012.037.012\" transform=\"translate(-2586.693 -35.158)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3403.907,176.785l.015-.046-.015.046\" transform=\"translate(-2527.843 79.883)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3547.763,103.042l.084.027-.084-.027\" transform=\"translate(-2642.704 138.726)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3550.108,103.823l.3.106c-.1-.036-.2-.072-.3-.106\" transform=\"translate(-2644.576 138.102)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3625.181,232.958c-.008.043-.017.087-.025.13.009-.043.017-.087.025-.13\" transform=\"translate(-2704.498 34.995)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3621.649,246.933l-.025.074.025-.074\" transform=\"translate(-2701.678 23.836)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3620.556,249.277c-.034.1-.068.2-.1.292.035-.1.07-.194.1-.292\" transform=\"translate(-2700.743 21.965)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3493.851,324.789c-.1-.016-.2-.033-.3-.051l.3.051\" transform=\"translate(-2599.415 -38.287)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3625.627,229.663c-.018.112-.037.223-.055.335q.029-.167.055-.335\" transform=\"translate(-2704.83 37.625)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3419.148,98.959l.168-.061.284-.1c.134-.047.27-.092.405-.136l.068-.022a22.868,22.868,0,0,1,2.563-.664l.044-.008c.195-.038.39-.074.586-.106l.256-.043.286-.042a23.072,23.072,0,0,1,6.628,0,23.059,23.059,0,0,0-24.947,14.838,23.178,23.178,0,0,1,13.659-13.655\" transform=\"translate(-2529.105 143.129)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3534.839,99.711l.049.009-.049-.009\" transform=\"translate(-2632.385 141.385)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3378.45,171.283q.177-.658.383-1.3a27.5,27.5,0,0,0-.829,3.244q.188-.974.447-1.942\" transform=\"translate(-2507.16 85.279)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3641.7,258.493q-.033.094-.068.188.034-.094.068-.188\" transform=\"translate(-2717.658 14.606)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3382.392,167.17q-.086.25-.167.5c.054-.168.11-.335.167-.5\" transform=\"translate(-2510.53 87.523)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3377.582,186.743q-.038.208-.074.416c.024-.139.048-.278.074-.416\" transform=\"translate(-2506.765 71.895)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3383.71,164.484c-.026.071-.052.142-.077.213.025-.071.051-.142.077-.213\" transform=\"translate(-2511.655 89.667)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3491.7,347.618c-.133-.019-.265-.038-.4-.059.132.021.265.04.4.059\" transform=\"translate(-2597.623 -56.508)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3377.1,190.691q-.013.082-.025.165.012-.082.025-.165\" transform=\"translate(-2506.415 68.743)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3647.776,235.611c.024-.127.046-.255.068-.383-.022.127-.044.256-.068.383\" transform=\"translate(-2722.559 33.182)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3486.982,346.793c-.25-.043-.5-.087-.751-.137q.374.073.751.137\" transform=\"translate(-2593.574 -55.787)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3467.973,341.72q.262.091.525.176c-.176-.057-.351-.116-.525-.176\" transform=\"translate(-2578.996 -51.846)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3648.457,232.654c.007-.043.013-.087.02-.131-.006.044-.013.087-.02.131\" transform=\"translate(-2723.103 35.342)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3465.284,340.76l.241.087-.241-.087\" transform=\"translate(-2576.849 -51.08)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3643.914,239.884q-.175.653-.38,1.292a27.452,27.452,0,0,0,.823-3.215q-.187.964-.443,1.923\" transform=\"translate(-2719.172 31)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3642.6,254.861c.054-.156.106-.314.158-.472q-.077.237-.158.472\" transform=\"translate(-2718.423 17.883)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3564.351,114.73a22.882,22.882,0,0,0-12-10.109,23.177,23.177,0,0,1,13.669,13.668l.056.156c.036.1.071.2.105.3q.068.2.132.394l.025.078a22.809,22.809,0,0,1,.687,2.683c.009.044.018.089.026.133.02.109.039.217.058.327s.039.225.056.337c.006.039.012.077.018.116a23.174,23.174,0,0,1,0,6.894,22.88,22.88,0,0,0-2.831-14.975\" transform=\"translate(-2646.368 137.465)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3473.89,343.463q-.448-.089-.9-.193t-.9-.225q-.662-.177-1.31-.385a27.492,27.492,0,0,0,3.1.8\" transform=\"translate(-2581.244 -52.597)\" fill=\"#0561fc\"\/>\n\t\t<path d=\"M3430.843,47.153c0-.008,0-.016,0-.024a27.367,27.367,0,0,0-2.011-9.915q-.049-.122-.1-.243c-.033-.08-.066-.16-.1-.239a28.071,28.071,0,0,0-5.588-8.434l-.018-.019c-.094-.1-.19-.192-.286-.288s-.194-.194-.293-.29l-.014-.014a27.259,27.259,0,0,0-2.9-2.453l2.081-2.08a2.306,2.306,0,1,0-3.261-3.261l-2.878,2.878q-.728-.359-1.48-.676l-.228-.1-.255-.1a27.4,27.4,0,0,0-8.039-1.921V15.282h4.611V10.67a4.617,4.617,0,0,0-4.611-4.611h-4.611a4.617,4.617,0,0,0-4.611,4.611v4.612h4.611v4.693a27.4,27.4,0,0,0-8.044,1.923l-.236.1-.247.1q-.749.317-1.475.674l-2.878-2.878a2.305,2.305,0,1,0-3.26,3.261l2.08,2.08a27.256,27.256,0,0,0-2.886,2.439l-.038.036c-.09.088-.179.178-.269.267a27.371,27.371,0,0,0-5.911,8.767l-.083.2c-.039.094-.078.189-.116.284q-.152.379-.292.764c-.027.071-.052.142-.077.213-.039.109-.078.219-.116.329-.057.167-.113.334-.168.5l-.021.064q-.207.645-.383,1.3-.26.967-.447,1.942c-.009.045-.018.089-.026.134-.026.139-.05.278-.074.416s-.043.253-.063.38c-.009.055-.017.11-.026.165-.051.334-.1.669-.136,1q-.078.676-.123,1.352-.022.338-.037.676t-.019.659c0,.008,0,.017,0,.025,0,.136,0,.272,0,.408,0,.086,0,.172,0,.257,0,.05,0,.1,0,.151,0,.008,0,.017,0,.026,0,.166,0,.332.01.5a27.362,27.362,0,0,0,2,9.408q.055.135.11.27l.089.212a28.1,28.1,0,0,0,5.6,8.446l.011.01c.1.1.195.2.293.3s.19.189.285.283l.022.021a27.373,27.373,0,0,0,8.6,5.657l.181.076c.094.038.189.075.284.112q.305.121.615.234l.241.087.3.106c.175.06.349.119.525.176l.042.014q.649.208,1.31.385.447.12.9.225t.895.193l.012,0c.25.05.5.094.751.137l.271.045c.132.021.265.04.4.059a27.628,27.628,0,0,0,3.939.293h.045a27.369,27.369,0,0,0,10.127-1.947c.1-.042.209-.082.314-.124l.167-.07q.788-.331,1.562-.711.821-.4,1.62-.866a27.807,27.807,0,0,0,5.76-4.413c.084-.084.169-.169.252-.254l.052-.054a27.378,27.378,0,0,0,5.566-8.41c.034-.081.068-.162.1-.243l.1-.239q.156-.389.3-.785c.023-.062.046-.125.068-.188.042-.118.085-.236.125-.355q.081-.235.158-.472l.031-.1q.2-.639.38-1.292.257-.958.443-1.923.016-.084.032-.168c.024-.128.046-.255.068-.383s.047-.276.069-.414c.007-.044.013-.087.02-.131a27.552,27.552,0,0,0,.318-3.71c0-.008,0-.016,0-.024,0-.136,0-.272,0-.409s0-.273,0-.409m-4.877,3.855c-.006.04-.012.079-.018.119q-.026.168-.055.335c-.019.11-.038.22-.059.329q-.012.065-.026.131-.156.806-.37,1.608-.146.545-.317,1.079l-.024.074c-.043.133-.088.266-.133.4-.034.1-.069.195-.1.292l-.057.16a23.062,23.062,0,0,1-25.068,14.83l-.148-.023-.3-.051c-.12-.021-.239-.042-.359-.064l-.1-.019q-.815-.157-1.625-.374-.552-.148-1.091-.321l-.037-.012q-.219-.071-.435-.146l-.255-.09-.2-.071a23.062,23.062,0,0,1-14.819-25.063q.011-.075.023-.149c.016-.1.033-.2.05-.3.021-.119.042-.238.064-.358l.019-.1q.157-.814.374-1.623.148-.55.32-1.088l.014-.045c.046-.143.094-.285.143-.427.03-.088.062-.176.093-.263l.068-.189a22.967,22.967,0,0,1,24.947-14.838l.285.042.257.043c.181.031.362.063.543.1l.038.007.049.009.108.024q.252.051.5.109l.2.045c.224.053.448.108.672.168q.543.145,1.075.316l.084.027c.13.042.26.086.389.13.1.034.2.07.3.106l.15.054a23.061,23.061,0,0,1,14.832,25.084\" transform=\"translate(-2505.151 216.162)\" fill=\"#00205b\"\/>\n\t\t<path d=\"M3444.277,117.186c-.006-.039-.012-.078-.018-.116-.017-.113-.036-.225-.056-.337s-.038-.218-.059-.327c-.008-.045-.017-.089-.025-.133q-.157-.805-.37-1.606-.146-.544-.316-1.077l-.025-.078q-.065-.2-.132-.394c-.035-.1-.069-.2-.1-.3l-.056-.155A23.174,23.174,0,0,0,3429.446,99l-.15-.054-.3-.106q-.193-.067-.389-.13l-.083-.027q-.532-.17-1.075-.316-.335-.09-.672-.168l-.2-.046q-.251-.057-.5-.109l-.2-.04c-.181-.036-.362-.068-.544-.1l-.257-.043c-.1-.016-.191-.028-.285-.042a23.072,23.072,0,0,0-6.628,0c-.095.014-.19.027-.285.042l-.257.043c-.2.033-.391.068-.585.107l-.044.009q-.743.148-1.482.346-.546.146-1.081.318l-.067.022c-.136.044-.271.089-.406.136l-.283.1L3413.5,99a23.176,23.176,0,0,0-13.659,13.655l-.068.189c-.032.087-.062.175-.093.263-.049.142-.1.284-.143.427l-.015.046q-.172.538-.32,1.088-.217.809-.374,1.623c-.006.034-.013.068-.02.1-.022.119-.043.238-.064.357-.017.1-.034.2-.05.3-.008.05-.015.1-.023.15a23.134,23.134,0,0,0,0,6.861c.008.051.015.1.023.152.016.1.033.2.05.3.021.12.042.24.064.36.006.033.013.066.019.1q.158.814.374,1.625.148.551.32,1.09l.014.041c.047.145.095.288.144.431.03.087.061.173.092.259l.07.193a23.177,23.177,0,0,0,13.649,13.65l.2.071.255.09q.217.075.435.146l.037.012q.54.173,1.091.321.81.216,1.626.374l.1.019c.12.023.239.044.359.064l.3.051.148.023a23.164,23.164,0,0,0,6.868,0l.139-.021c.105-.017.21-.034.315-.053s.232-.04.348-.062l.111-.021q.812-.157,1.619-.372.548-.148,1.086-.319l.053-.017q.21-.068.419-.14l.273-.1.179-.064a23.178,23.178,0,0,0,13.659-13.663l.058-.16q.053-.145.1-.292.068-.2.133-.4l.024-.074q.171-.534.317-1.079.215-.8.371-1.608c.008-.043.017-.087.025-.13.021-.11.04-.219.059-.329s.038-.223.055-.335c.006-.04.013-.079.019-.119a23.164,23.164,0,0,0,0-6.894m-9.974-6.619a2.306,2.306,0,1,1-.844,3.15,2.3,2.3,0,0,1,.844-3.15m-22.047-5.907a2.306,2.306,0,1,1-.844,3.149,2.293,2.293,0,0,1,.844-3.149m-9.223,15.974a2.306,2.306,0,1,1,2.306,2.306,2.305,2.305,0,0,1-2.306-2.306m5.621,10.066a2.306,2.306,0,1,1,.844-3.149,2.294,2.294,0,0,1-.844,3.149m.844-16.983a2.306,2.306,0,1,1-.844-3.15,2.3,2.3,0,0,1,.844,3.15m5.908,22.047a2.307,2.307,0,1,1-.844-3.149,2.306,2.306,0,0,1,.844,3.149m6.073,3.315a2.306,2.306,0,1,1,2.306-2.306,2.306,2.306,0,0,1-2.306,2.306m0-11.528a6.914,6.914,0,0,1-2.3-13.434V103.065a2.3,2.3,0,0,1,2.3-2.3h0a2.3,2.3,0,0,1,2.3,2.3v1.422s0,.005,0,.007,0,0,0,.007v9.613a6.916,6.916,0,0,1-2.307,13.437m9.224,9.057a2.306,2.306,0,1,1,.844-3.15,2.29,2.29,0,0,1-.844,3.15m.844-28.8a2.306,2.306,0,1,1-.844-3.149,2.3,2.3,0,0,1,.844,3.149m5.908,22.047a2.307,2.307,0,1,1-.844-3.15,2.3,2.3,0,0,1,.844,3.15m.165-6.917a2.306,2.306,0,1,1,2.306-2.306,2.305,2.305,0,0,1-2.306,2.306\" transform=\"translate(-2523.462 143.089)\" fill=\"#1f79af\"\/>\n\t\t<path d=\"M3488.865,127.254a6.9,6.9,0,0,0-1.154-.529v-11.05a2.3,2.3,0,0,0-2.3-2.3h0a2.3,2.3,0,0,0-2.3,2.3v11.052a6.913,6.913,0,1,0,5.765.527M3487.4,134.4a2.307,2.307,0,1,1-.844-3.15,2.3,2.3,0,0,1,.844,3.15\" transform=\"translate(-2587.39 130.479)\" fill=\"#efc025\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h2 class=\"co-columns--box_headline\" >Tramitaci\u00f3n r\u00e1pida de reclamaciones<\/h2><div class=\"co-columns--box_desc\"><p>En caso de accidente o da\u00f1os, garantizamos un proceso de reclamaci\u00f3n \u00e1gil para que pueda volver a la carretera lo antes posible.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__long-form-text co-flex_row__next_row__faqs\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-long_form\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Proteja su viaje con un seguro de auto de Sound Insurance Services.<\/h2><div class=\"co-intro_text--intro\"><p>Con un enfoque centrado en el cliente, priorizamos sus necesidades y trabajamos para ofrecerle soluciones personalizadas que se adapten a sus circunstancias particulares.<\/p>\n<\/div>\t\t<\/header>\n\t\t\t\t<div class=\"co-long_form--block co-long_form--block__nomedia prow items-start\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:8\">\n\t\t\t\t\t<div class=\"co-long_form--content\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5313\" src=\"https:\/\/www.soundcu.com\/files\/SIS_Logo_Horiz_GradientBlue_250x66.png\" alt=\"sound insurance services logo\" width=\"250\" height=\"66\" srcset=\"https:\/\/www.soundcu.com\/files\/SIS_Logo_Horiz_GradientBlue_250x66.png 250w, https:\/\/www.soundcu.com\/files\/SIS_Logo_Horiz_GradientBlue_250x66-75x20.png 75w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__faqs co-flex_row__next_row__single-path-cta\" id=\"faqs\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<section class=\"co-accords_section\" aria-label=\"\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<div class=\"co-intro_text--intro\"><p>Preguntas frecuentes sobre seguros de autom\u00f3viles<\/p>\n<\/div>\t\t<\/header>\n\t\t\t<div class=\"co-accordion\" data-animation=\"on\" data-multi-items=\"on\">\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"3507\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfQu\u00e9 es un seguro personal?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>Con una p\u00f3liza de seguro personal, usted y su familia pueden protegerse de posibles responsabilidades y recibir una compensaci\u00f3n justa en caso de siniestro. El seguro individual cubre gastos que podr\u00edan afectar gravemente su situaci\u00f3n financiera.<\/p>\n<p>Algunas p\u00f3lizas, como los seguros de auto y de hogar, son obligatorias por ley o por exigencias de terceros. Los accidentes ocurren, y es importante protegerse contra sus devastadoras consecuencias financieras.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4032\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfCu\u00e1nto duran los pr\u00e9stamos para autom\u00f3viles?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>La mayor\u00eda de los pr\u00e9stamos para autom\u00f3viles est\u00e1n disponibles en plazos de 12 meses, con una duraci\u00f3n de entre dos y ocho a\u00f1os.<\/p>\n<p>Sound Credit Union ofrece pr\u00e9stamos para autom\u00f3viles. <a href=\"https:\/\/www.soundcu.com\/es\/personal\/auto-loans\/\">M\u00e1s informaci\u00f3n \u00bb<\/a><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"co-accordion--item\">\n\t\t\t\t\t<button\n\t\t\t\t\t\t\t\t\t\t\t\t\tdata-accordid=\"4089\"\n\t\t\t\t\t\t\t\t\t\t\t\tclass=\"co-accordion--header\t\t\t\t\t\t\tjs-accord_toggle\t\t\t\t\t\t\tclosed\"\n\t\t\t\t\t>\n\t\t\t\t\t\t<span class=\"text-md\">\u00bfCu\u00e1nto duran los pr\u00e9stamos para autocaravanas, barcos y motocicletas?<\/span>\n\t\t\t\t\t\t<svg class=\"co-accordion--icon no-js:is-hidden\" viewbox=\"0 0 20 20\"><g class=\"icon__group\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"3\" y1=\"3\" x2=\"17\" y2=\"17\"><\/line><line x1=\"17\" y1=\"3\" x2=\"3\" y2=\"17\"><\/line><\/g><\/svg>\n\t\t\t\t\t<\/button>\n\t\t\t\t\t<div class=\"co-accordion--panel\t\t\t\t\t\tjs-accord_content\">\n\t\t\t\t\t\t<p>Los pr\u00e9stamos para autocaravanas y embarcaciones suelen tener plazos de entre 10 y 15 a\u00f1os, mientras que los pr\u00e9stamos para motocicletas suelen durar entre 36 y 60 meses.<\/p>\n<p>Los socios de Sound Credit Union ofrecen <a href=\"https:\/\/www.soundcu.com\/es\/personal\/rv-boat-and-motorcycle-loans\/\">Pr\u00e9stamos para veh\u00edculos recreativos, barcos y motocicletas<\/a>. Obt\u00e9n m\u00e1s informaci\u00f3n hoy mismo.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/section>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__single-path-cta co-flex_row__next_row__disclosures\" id=\"quote\">\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<svg class=\"co-sp_cta__svg\" width=\"488.512\" height=\"338.101\" viewbox=\"0 0 488.512 338.101\">\n\t\t\t<path class=\"co-sp_cta__svg--path_big\" d=\"M488.512,163.324C337.738,308.387,172.875,346.284,6.386,332.445c-12.895-1.072-2.726.507,0-169.121C7.666,83.681-1.682,4.826,3.448,4.309,177.337-13.221,346.255,19.454,488.512,163.324Z\"\/>\n\t\t\t<path class=\"co-sp_cta__svg--path_small\" d=\"M408.431,63.648c-126.358,121.572-278.108,50-408.431,0C129.644,19.327,291.966-54.138,408.431,63.648Z\" transform=\"translate(0 207.52)\" fill=\"#efc025\"\/>\n\t<\/svg>\n\t<div class=\"co-sp_cta\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">\u00bfTiene alguna pregunta o est\u00e1 listo para obtener una cotizaci\u00f3n de p\u00f3liza?<\/h2><div class=\"co-intro_text--intro\"><p>Nuestro objetivo es simplificar el proceso de seguros, ofreciendo claridad y transparencia en cada paso del camino.<\/p>\n<\/div>\t\t<\/header>\n\t<a class=\"co-sp_cta--button gtm-button\" href=\"https:\/\/www.soundcu.com\/es\/speed-bump\/?url=https%3A%2F%2Fwww.soundcu.com%2Fpersonal%2Finsurance%2F&#038;prev=https%3A%2F%2Fwww.soundcu.com%2Fes%2Fpersonal%2Finsurance%2Fauto%2F\"  >Seguro<\/a><a class=\"co-sp_cta--link\" href=\"https:\/\/www.soundcu.com\/es\/speed-bump\/?url=https%3A%2F%2Fwww.soundcu.com%2Fpersonal%2Finsurance%2Fauto%2F&#038;prev=https%3A%2F%2Fwww.soundcu.com%2Fes%2Fpersonal%2Finsurance%2Fauto%2F\"  >Seguro de autom\u00f3vil<\/a>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t<div class=\"small-text\">\n<p>Los productos de seguros no son dep\u00f3sitos, no constituyen una obligaci\u00f3n ni est\u00e1n garantizados por Sound Credit Union. No est\u00e1n protegidos por la NCUA, pueden estar sujetos a riesgos y, en el caso de los seguros de vida, su valor puede disminuir. Cualquier seguro requerido como condici\u00f3n para la concesi\u00f3n de cr\u00e9dito no tiene que adquirirse necesariamente en la cooperativa de cr\u00e9dito y puede contratarse con un agente o compa\u00f1\u00eda de seguros de su elecci\u00f3n. Los productos de seguros no son exclusivos para los miembros de Sound Credit Union. Las transacciones con Sound Insurance Services son independientes y distintas de cualquier transacci\u00f3n con la cooperativa de cr\u00e9dito. Sound Insurance Services es una filial de Sound Credit Union.<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":2346,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_searchwp_excluded":"","footnotes":""},"county":[],"class_list":["post-2349","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/comments?post=2349"}],"version-history":[{"count":0,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2349\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2346"}],"wp:attachment":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/media?parent=2349"}],"wp:term":[{"taxonomy":"county","embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/county?post=2349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}