{"id":2350,"date":"2023-08-14T18:12:40","date_gmt":"2023-08-15T01:12:40","guid":{"rendered":"https:\/\/www.soundcu.com\/personal\/insurance\/add\/"},"modified":"2025-11-14T15:04:01","modified_gmt":"2025-11-14T23:04:01","slug":"add","status":"publish","type":"page","link":"https:\/\/www.soundcu.com\/es\/personal\/insurance\/add\/","title":{"rendered":"Seguro de muerte accidental y desmembramiento"},"content":{"rendered":"<div class=\"co-flex_row co-flex_row__blue co-flex_row__page-hero co-flex_row__next_row__page-intro\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<header class=\"co-page_hero  co-page_hero__has_image\" aria-label=\"Encabezado: Muerte y desmembramiento accidentales\">\n\t\t<div class=\"co-page_hero--inner\">\n\t\t\t<div class=\"prow items-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-page_hero--img_wrap pcol-lg:6 pcol-xl:7\">\n\t\t\t\t\t\t<div class=\"co-page_hero--mask\"><svg width=\"997.021\" height=\"609.682\" viewbox=\"0 0 997.021 609.682\"><defs><clippath id=\"svgPathHero\"><path d=\"M299.014.148H0V609.681H299.014c480.632.192,698.007-296.752,698.007-296.752C691.761-16.846,299.014.148,299.014.148\"\/><\/clippath><\/defs><image id=\"image_6a03d43df0f22\" xlink:href=\"https:\/\/www.soundcu.com\/files\/add-insurance.jpg\" src=\"https:\/\/www.soundcu.com\/files\/add-insurance.jpg\" clip-path=\"url(#svgPathHero)\"  alt=\"Two people riding mountain bikes on an open field\" \/><\/svg><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"co-page_hero--text pcol-lg:6 pcol-xl:5\">\n\t\t\t\t\t\t\t\t\t\t\t<h1 class=\"co-page_hero--sup_heading\">\n\t\t\t\t\t\t\tSeguro de muerte accidental y desmembramiento\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"co-page_hero--title\" >Muerte accidental y desmembramiento<\/h2>\t\t\t\t\t<p class=\"co-page_hero--tagline\">Cobertura para lo inesperado.<\/p>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/header>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__next_row_diff co-flex_row__page-intro co-flex_row__next_row__columns\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-page_intro\">\n\t\t<div class=\"co-page_intro--desc\"><p>\u00bfSab\u00edas que Sound ofrece 1000 d\u00f3lares de cobertura gratuita de seguro de accidentes y muerte accidental (AD&amp;D)? Es uno de los muchos beneficios de ser miembro de Sound. \u00a1Activa tu cobertura hoy mismo!<\/p>\n<\/div>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__white co-flex_row__next_row_diff co-flex_row__columns co-flex_row__next_row__long-form-text\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-columns\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Muerte accidental y desmembramiento<\/h2>\t\t<\/header>\n\t\t\t\t<div class=\"co-columns--row prow prow-md:2 prow-lg:3 co-columns--row__icons justify-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconDocument\"\n\t\tviewbox=\"0 0 68.424 72.069\"\n\t\twidth=\"68.424\"\n\t\theight=\"72.069\"\n\t>\n\t\t<title>Document<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-328.544 -815.728)\">\n\t\t\t<path d=\"M981.1,2956.052v.133h-.047v4.933h9.235v-5.542a4.659,4.659,0,0,0-4.085-4.726v.1a5.1,5.1,0,0,0-5.1,5.1\" transform=\"translate(-593.321 -2135.101)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M765.062,3308.245h0Z\" transform=\"translate(-420.862 -2420.462)\" fill=\"#eaf4fe\"\/>\n\t\t\t<path d=\"M736.068,3268.881v-1.625H687.387v1.625a6.636,6.636,0,0,0,6.636,6.636h43.684c.244,0,3.176.03,3.176,0l-.094-.023c-1.383-.341-4.72-.975-4.72-6.613\" transform=\"translate(-358.843 -2387.735)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M776.036,2950.743h-37.23a6.636,6.636,0,0,0-6.636,6.636v57.157h39.655v1.625c0,5.638,3.337,6.272,4.72,6.613a6.506,6.506,0,0,0,5.788-6.613V2956.1h.047v-.133a5.1,5.1,0,0,1,5.1-5.1v-.12Zm-35.095,12.344h15.792v3.158H740.941Zm0,12.653h23.689v3.158H740.941Zm0,5.8h15.792v3.158H740.941Zm14.213,23.688H740.941v-3.158h14.213Zm9.476-7.877H740.941v-3.158H764.63Zm6.317-6.342H740.941v-3.158h30.006Z\" transform=\"translate(-394.599 -2135.015)\" fill=\"#1f79af\"\/>\n\t\t\t<rect width=\"15.792\" height=\"3.158\" transform=\"translate(346.342 846.525)\" fill=\"#efc025\"\/>\n\t\t\t<rect width=\"30.006\" height=\"3.158\" transform=\"translate(346.342 852.837)\" fill=\"#efc025\"\/>\n\t\t\t<rect width=\"23.689\" height=\"3.158\" transform=\"translate(346.342 859.178)\" fill=\"#efc025\"\/>\n\t\t\t<rect width=\"14.213\" height=\"3.159\" transform=\"translate(346.342 867.055)\" fill=\"#efc025\"\/>\n\t\t\t<rect width=\"15.792\" height=\"3.158\" transform=\"translate(346.342 828.072)\" fill=\"#efc025\"\/>\n\t\t\t<rect width=\"23.689\" height=\"3.158\" transform=\"translate(346.342 840.725)\" fill=\"#efc025\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Preautorizado para mayor protecci\u00f3n<\/h3><div class=\"co-columns--box_desc\"><p>Usted est\u00e1 preautorizado para una cobertura adicional de hasta $300,000.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconStarTeamwork\"\n\t\tviewbox=\"0 0 72.388 72.388\"\n\t\twidth=\"72.388\"\n\t\theight=\"72.388\"\n\t>\n\t\t<title>Star Teamwork<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-197.847 -1006.406)\">\n\t\t\t<path d=\"M108.474,3918.9q-.515-1.218-1.115-2.389t-1.28-2.291q-.453-.747-.941-1.469-.732-1.083-1.538-2.11-.537-.683-1.106-1.34-.284-.329-.576-.65-.584-.643-1.2-1.257-.921-.922-1.907-1.775-.657-.569-1.341-1.107-1.026-.805-2.109-1.538a36.1,36.1,0,0,0-3.759-2.221q-.39-.2-.786-.391-1.582-.762-3.247-1.373t-3.4-1.057a35.991,35.991,0,0,0-3.533-.722,36.638,36.638,0,0,0-11.024,0,36,36,0,0,0-3.534.722q-1.734.446-3.4,1.057t-3.247,1.373q-.4.191-.786.391a36.106,36.106,0,0,0-3.759,2.221q-1.083.732-2.109,1.538-.684.538-1.341,1.107-.985.853-1.907,1.775-.614.614-1.2,1.257-.292.322-.577.65-.569.657-1.106,1.34-.806,1.026-1.538,2.11-.488.722-.941,1.469-.68,1.12-1.28,2.291t-1.115,2.389a36.194,36.194,0,1,0,66.7,0m-5.772,20.48q-.158.685-.349,1.356a28.192,28.192,0,0,1-4.148,8.636q-.395.554-.815,1.09t-.865,1.048q-.445.514-.913,1.005t-.96.96q-.983.938-2.053,1.779-.534.42-1.09.814t-1.129.763q-1.149.736-2.37,1.362-.61.313-1.237.6-.94.426-1.916.783-.65.238-1.315.445t-1.343.381q-.678.175-1.369.316t-1.394.249q-.7.108-1.416.18a28.694,28.694,0,0,1-2.894.146,28.3,28.3,0,0,1-28.3-28.3,28.667,28.667,0,0,1,.146-2.894q.073-.713.18-1.416t.249-1.394q.142-.691.316-1.369t.381-1.344q.207-.664.445-1.315.357-.975.783-1.916.283-.627.6-1.237.625-1.221,1.362-2.37.368-.574.763-1.129t.815-1.09q.84-1.069,1.779-2.053.469-.492.96-.96t1.005-.913q.514-.445,1.048-.865t1.09-.815a28.2,28.2,0,0,1,8.636-4.148q.671-.191,1.356-.349a28.593,28.593,0,0,1,9.285-.579q.713.073,1.416.18t1.394.249q.346.07.688.15,1.027.237,2.025.548.665.207,1.315.445.975.356,1.916.783.627.283,1.237.6,1.221.625,2.37,1.362.574.368,1.129.763t1.09.815q.535.42,1.048.865t1.005.913q.492.468.96.96t.913,1.005q.445.513.865,1.048t.815,1.09q.395.555.763,1.129.736,1.149,1.363,2.37.312.61.6,1.237.425.94.783,1.916.238.65.445,1.315.31,1,.548,2.025.079.342.15.688.142.69.249,1.394t.18,1.416a28.6,28.6,0,0,1-.579,9.286\" transform=\"translate(158.917 -2890.388)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M134.363,3959.94q-.107-.7-.249-1.394-.071-.346-.15-.688-.237-1.027-.548-2.025-.207-.664-.445-1.315-.357-.976-.783-1.916-.283-.627-.6-1.237-.625-1.221-1.363-2.37-.368-.574-.763-1.129t-.815-1.09q-.42-.535-.865-1.049t-.913-1.005q-.469-.491-.96-.96t-1.005-.913q-.513-.445-1.048-.865t-1.09-.815q-.555-.394-1.129-.763-1.148-.736-2.37-1.363-.61-.312-1.237-.6-.94-.425-1.916-.782-.65-.238-1.315-.445-1-.31-2.025-.548-.343-.079-.688-.15-.691-.141-1.394-.249t-1.416-.18a28.6,28.6,0,0,0-9.286.578q-.685.158-1.356.349A28.181,28.181,0,0,0,90,3941.169q-.555.395-1.09.815t-1.048.865q-.513.444-1.005.913t-.96.96q-.937.984-1.779,2.054-.42.534-.815,1.09T82.543,3949q-.736,1.148-1.362,2.37-.313.61-.6,1.237-.425.94-.783,1.916-.238.65-.445,1.315t-.381,1.343q-.174.678-.316,1.37t-.249,1.394q-.107.7-.18,1.416a28.608,28.608,0,0,0-.146,2.894,28.3,28.3,0,0,0,28.3,28.3,28.623,28.623,0,0,0,2.894-.146q.713-.073,1.416-.18t1.394-.249q.691-.141,1.369-.316t1.343-.382q.665-.207,1.315-.445.975-.357,1.916-.783.627-.283,1.237-.6,1.221-.625,2.37-1.362.574-.368,1.129-.762t1.09-.815q1.069-.84,2.053-1.778.492-.469.96-.96t.913-1.006q.445-.513.865-1.049t.815-1.089a28.187,28.187,0,0,0,4.148-8.635q.19-.672.349-1.357a28.6,28.6,0,0,0,.579-9.286q-.073-.713-.18-1.416m-9.1,23.183a26.69,26.69,0,1,1,7.817-18.872,26.515,26.515,0,0,1-7.817,18.872\" transform=\"translate(127.654 -2921.65)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M284.8,4194.67q-1.149.736-2.37,1.362,1.22-.625,2.37-1.362\" transform=\"translate(-35.508 -3128.226)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M325.551,4163.065c-.28.356-.569.707-.865,1.048.3-.342.585-.692.865-1.048\" transform=\"translate(-69.245 -3102.991)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M300.885,4186.843q-.534.42-1.09.814.555-.395,1.09-.814\" transform=\"translate(-49.371 -3121.977)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M329.793,4157.659q-.395.554-.815,1.089.42-.535.815-1.089\" transform=\"translate(-72.672 -3098.675)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M268.7,4204.388q-.94.425-1.916.783.975-.357,1.916-.783\" transform=\"translate(-23.016 -3135.986)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M353.951,4108.083q-.158.685-.349,1.356.191-.671.349-1.356\" transform=\"translate(-92.333 -3059.091)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M234.28,4215.175q-.7.107-1.417.18.714-.072,1.417-.18\" transform=\"translate(4.071 -3144.598)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M328.978,3989.675q.42.534.815,1.09-.395-.555-.815-1.09\" transform=\"translate(-72.672 -2964.549)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M336.806,4000.684q.736,1.148,1.362,2.37-.625-1.22-1.362-2.37\" transform=\"translate(-78.922 -2973.339)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M324.686,3984.474q.445.513.865,1.048-.42-.535-.865-1.048\" transform=\"translate(-69.245 -2960.396)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M305.2,3965.9q.535.42,1.048.865-.513-.445-1.048-.865\" transform=\"translate(-53.687 -2945.564)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M346.524,4018.581q.425.94.783,1.916-.357-.975-.783-1.916\" transform=\"translate(-86.681 -2987.628)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M282.434,3951.31q1.22.625,2.37,1.363-1.149-.736-2.37-1.363\" transform=\"translate(-35.509 -2933.916)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M299.795,3961.855q.555.395,1.09.815-.534-.42-1.09-.815\" transform=\"translate(-49.371 -2942.336)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M352.615,4034.613q.31,1,.548,2.025-.237-1.028-.548-2.025\" transform=\"translate(-91.545 -3000.429)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M266.788,3944.469q.975.357,1.916.783-.94-.425-1.916-.783\" transform=\"translate(-23.016 -2928.454)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M315.389,4174.214q.492-.469.96-.96-.469.491-.96.96\" transform=\"translate(-61.822 -3111.126)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M316.349,3975.683q-.469-.491-.96-.96.491.469.96.96\" transform=\"translate(-61.822 -2952.61)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M117.819,3974.723q-.492.469-.96.96.469-.491.96-.96\" transform=\"translate(96.694 -2952.61)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M254.942,4210.479q-.664.207-1.343.381.678-.175,1.343-.381\" transform=\"translate(-12.486 -3140.849)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M356.076,4048.07q.141.691.249,1.394-.107-.7-.249-1.394\" transform=\"translate(-94.308 -3011.174)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M357.31,4054.985q.107.7.18,1.417-.072-.714-.18-1.417\" transform=\"translate(-95.293 -3016.695)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M82.5,4035.955q.174-.679.381-1.343-.207.665-.381,1.343\" transform=\"translate(124.124 -3000.428)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M79.7,4049.463q.107-.7.249-1.394-.141.691-.249,1.394\" transform=\"translate(126.362 -3011.174)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M86.6,4020.5q.357-.975.783-1.916-.425.94-.783,1.916\" transform=\"translate(120.85 -2987.628)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M241.285,4213.94q-.691.141-1.394.249.7-.107,1.394-.249\" transform=\"translate(-1.541 -3143.613)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M93.446,4003.054q.625-1.22,1.362-2.37-.736,1.149-1.362,2.37\" transform=\"translate(115.388 -2973.339)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M250.219,3939.544q1.027.237,2.025.548-1-.31-2.025-.548\" transform=\"translate(-9.787 -2924.521)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M78.809,4056.4q.073-.713.18-1.417-.107.7-.18,1.417\" transform=\"translate(127.075 -3016.695)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M232.863,3936.673q.714.073,1.417.18-.7-.107-1.417-.18\" transform=\"translate(4.071 -2922.229)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M239.891,3937.566q.7.107,1.394.249-.691-.142-1.394-.249\" transform=\"translate(-1.541 -2922.942)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M180.064,3939.893q.671-.19,1.356-.349-.685.158-1.356.349\" transform=\"translate(46.228 -2924.521)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M131.811,3962.67q.535-.42,1.09-.815-.555.395-1.09.815\" transform=\"translate(84.756 -2942.336)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M126.61,3966.763q.513-.445,1.048-.865-.535.42-1.048.865\" transform=\"translate(88.908 -2945.564)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M103.991,3990.766q.395-.555.815-1.089-.42.534-.815,1.089\" transform=\"translate(106.969 -2964.55)\" fill=\"#ffc400\"\/>\n\t\t\t<path d=\"M150.9,3994.509l-5.72-11.59-5.72,11.59-12.79,1.859,9.255,9.021-2.185,12.739,11.44-6.014,11.44,6.014-2.185-12.739,9.255-9.021Z\" transform=\"translate(88.863 -2959.154)\" fill=\"#1f79af\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >No se requieren ex\u00e1menes m\u00e9dicos.<\/h3><div class=\"co-columns--box_desc\"><p>Usted est\u00e1 preautorizado para Cobertura Adicional hasta $300,000<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"co-columns--box\">\n\t\t\t\t\t\t\t<svg\n\t\tclass=\"co-columns--box_icon IconHandWithDollar\"\n\t\tviewbox=\"0 0 70.308 70.764\"\n\t\twidth=\"70.308\"\n\t\theight=\"70.764\"\n\t>\n\t\t<title>Hand with Dollar<\/title>\n\t\tclase=\u201denvoltorio\u201d&gt;\n\t<g transform=\"translate(-686.671 -430.658)\">\n\t\t\t<path d=\"M2550.55,1105.646h6.015a6.333,6.333,0,0,1,3.644-3.516V1086.2a6.364,6.364,0,0,1-3.61-3.439h-45.751a6.36,6.36,0,0,1-3.61,3.439v15.926a6.337,6.337,0,0,1,3.644,3.516h28.873v-.257a4.64,4.64,0,0,1,4.635-4.635h1.527a4.64,4.64,0,0,1,4.634,4.635Zm-28.615-9.895h-11.345v-3.09h11.345Zm11.787,7.574a9.121,9.121,0,1,1,9.22-9.119,9.18,9.18,0,0,1-9.22,9.119m11.788-10.664h11.344v3.09h-11.344Z\" transform=\"translate(-1811.898 -643.532)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M2614.361,1109.6a6.031,6.031,0,1,0,6.13,6.032,6.088,6.088,0,0,0-6.13-6.032\" transform=\"translate(-1892.537 -664.962)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M2464.232,1040.22v40.031h41.185v-5.485H2474.1l-.229-1.27a3.249,3.249,0,0,0-2.745-2.619l-1.32-.195V1049.71l1.321-.193a3.254,3.254,0,0,0,2.733-2.567l.246-1.245h50.549l.247,1.244a3.256,3.256,0,0,0,2.733,2.567l1.321.193v20.975l-1.32.194a3.244,3.244,0,0,0-2.743,2.617l-.229,1.271h-8.455v5.485h18.327V1040.22Z\" transform=\"translate(-1777.561 -609.562)\" fill=\"#efc025\"\/>\n\t\t\t<path d=\"M2624.533,1245.258c.4-.662.757-1.2,1.04-1.6.081-.115.158-.222.225-.312v-4.51h-7.328l-2.022,1.429-.093.093a4.643,4.643,0,0,0,0,6.554l1.079,1.08a4.639,4.639,0,0,0,5.314.881,25.27,25.27,0,0,1,1.787-3.612\" transform=\"translate(-1897.941 -768.144)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M2668.855,1264.156\" transform=\"translate(-1940.942 -788.363)\" fill=\"#0450cf\"\/>\n\t\t\t<path d=\"M2674.169,1197.726v5.032h-3.09v-13.864a1.546,1.546,0,0,0-1.544-1.545h-1.527a1.546,1.546,0,0,0-1.545,1.545V1203.3l-.344.425c-.06.074-6.061,7.649-3.359,14.406l.11.276v3.89h14.9v-2.619l5.495-8.426a13.577,13.577,0,0,0,2.211-7.437v-6.093Z\" transform=\"translate(-1935.518 -727.037)\" fill=\"#1f79af\"\/>\n\t\t\t<path d=\"M2657.26,1172.019h-1.527a4.64,4.64,0,0,0-4.635,4.635V1190c-.066.09-.143.2-.225.313-.282.4-.644.94-1.039,1.6a25.2,25.2,0,0,0-1.787,3.612,15.605,15.605,0,0,0-.542,11.234v3.3h3.09v-3.89l-.111-.276c-2.7-6.756,3.3-14.332,3.359-14.406l.344-.425v-14.411a1.546,1.546,0,0,1,1.545-1.545h1.527a1.547,1.547,0,0,1,1.545,1.545v13.864h3.089v-13.864a4.639,4.639,0,0,0-4.634-4.635\" transform=\"translate(-1923.243 -714.797)\" fill=\"#00205b\"\/>\n\t\t\t<path d=\"M2654.49,1360.767h-21.584v6.158h25.181v-6.158Z\" transform=\"translate(-1912.238 -865.502)\" fill=\"#00205b\"\/>\n\t<\/g>\n\t<\/symbol>\t<\/svg>\n<h3 class=\"co-columns--box_headline\" >Beneficios para los beneficiarios<\/h3><div class=\"co-columns--box_desc\"><p>Las prestaciones se pagan a su beneficiario si usted fallece a causa de un accidente cubierto.<\/p>\n<\/div><div class=\"co-columns--box_button\"><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__long-form-text co-flex_row__next_row__single-path-cta\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-long_form\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Proteja a su familia de lo inesperado<\/h2><div class=\"co-intro_text--intro\"><p>Sound Credit Union puede ayudar a proteger a su familia con una cobertura de seguro de accidentes y muerte accidental (AD&amp;D) de $2,000 pagada por Sound Credit Union.<\/p>\n<\/div>\t\t<\/header>\n\t\t\t\t<div class=\"co-long_form--block co-long_form--block__nomedia prow items-start\">\n\t\t\t\t<div class=\"co-long_form--text pcol-md:12\">\n\t\t\t\t\t<h3 class=\"co-long_form--headline\" >Asegurado por Minnesota Life Insurance Company<\/h3><div class=\"co-long_form--content\"><p style=\"text-align: left;\">Como socio de Sound Credit Union mayor de 18 a\u00f1os, puede proteger el futuro financiero de su familia con un seguro de Muerte y Desmembramiento Accidental (AD&amp;D) suscrito por Minnesota Life Insurance Company. Adem\u00e1s de la cobertura de $2,000 que paga la cooperativa de cr\u00e9dito, puede adquirir cobertura adicional a precios grupales.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul style=\"text-align: left;\">\n<li>Usted est\u00e1 preautorizado para una cobertura adicional de hasta $300,000<\/li>\n<li>Su admisi\u00f3n est\u00e1 garantizada; no se requieren ex\u00e1menes m\u00e9dicos ni preguntas sobre su salud.<\/li>\n<li>Las prestaciones se pagan a su beneficiario si usted fallece a causa de un accidente cubierto.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: left;\">No se le puede negar la cobertura pagada por la cooperativa de cr\u00e9dito, ni ninguna cobertura adicional que usted seleccione. Toda la cobertura se reduce en 50% a partir de los 70 a\u00f1os, independientemente de la edad al momento de la inscripci\u00f3n.<\/p>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__single-path-cta co-flex_row__next_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<svg class=\"co-sp_cta__svg\" width=\"488.512\" height=\"338.101\" viewbox=\"0 0 488.512 338.101\">\n\t\t\t<path class=\"co-sp_cta__svg--path_big\" d=\"M488.512,163.324C337.738,308.387,172.875,346.284,6.386,332.445c-12.895-1.072-2.726.507,0-169.121C7.666,83.681-1.682,4.826,3.448,4.309,177.337-13.221,346.255,19.454,488.512,163.324Z\"\/>\n\t\t\t<path class=\"co-sp_cta__svg--path_small\" d=\"M408.431,63.648c-126.358,121.572-278.108,50-408.431,0C129.644,19.327,291.966-54.138,408.431,63.648Z\" transform=\"translate(0 207.52)\" fill=\"#efc025\"\/>\n\t<\/svg>\n\t<div class=\"co-sp_cta\">\n\t\t\t\t<header class=\"co-intro_text\">\n\t\t\t<h2 class=\"co-intro_text--title\">Reg\u00edstrate para obtener tu cobertura gratuita.<\/h2><div class=\"co-intro_text--intro\"><p>Recuerda, la cobertura $2,000 es gratuita. \u00a1Corre por nuestra cuenta!<\/p>\n<\/div>\t\t<\/header>\n\t<a class=\"co-sp_cta--button gtm-button\" href=\"https:\/\/www.soundcu.com\/es\/speed-bump\/?url=https%3A%2F%2Fwww.soundcu.com%2Fspeed-bump%2F%3Furl%3Dhttps%253A%252F%252Fwww.myonlineinsurance.com%252Fsoundcu%252Fadd%26prev%3Dhttps%253A%252F%252Fwww.soundcu.com%252Fpersonal-insurance%252Fprotection-services%252F&#038;prev=https%3A%2F%2Fwww.soundcu.com%2Fes%2Fpersonal%2Finsurance%2Fadd%2F\" target=\"_blank\" >Inscr\u00edbete ahora<\/a>\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"co-flex_row co-flex_row__blue co-flex_row__last co-flex_row__disclosures\" >\n\t<div class=\"co-flex_row--row co-row\">\n\t\t\t<div class=\"co-disclosures\">\n\t\t<h2 class=\"co-disclosures--title\">Divulgaciones<\/h2>\n\t\t<div class=\"co-disclosures--content\">\n\t\t\t<div class=\"small-text\">\n<p>Robert Dudacek, Agente de Seguros con licencia #972576-TN<br \/>\n0620 503692<\/p>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":2346,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_searchwp_excluded":"","footnotes":""},"county":[],"class_list":["post-2350","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/comments?post=2350"}],"version-history":[{"count":2,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2350\/revisions"}],"predecessor-version":[{"id":17580,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2350\/revisions\/17580"}],"up":[{"embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/pages\/2346"}],"wp:attachment":[{"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/media?parent=2350"}],"wp:term":[{"taxonomy":"county","embeddable":true,"href":"https:\/\/www.soundcu.com\/es\/wp-json\/wp\/v2\/county?post=2350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}